{"id":60224,"date":"2016-08-30T13:10:10","date_gmt":"2016-08-30T11:10:10","guid":{"rendered":"https:\/\/www.onebigpark.at\/de\/?p=60224"},"modified":"2020-07-10T06:40:38","modified_gmt":"2020-07-10T04:40:38","slug":"vorbereitung-salzburger-festspiele","status":"publish","type":"post","link":"https:\/\/www.salzburgerland.com\/de\/vorbereitung-salzburger-festspiele\/","title":{"rendered":"Perfekt vorbereitet auf die Salzburger Festspiele"},"content":{"rendered":"<h2>Lesen und h\u00f6ren Sie sich ein<\/h2>\n<p>Die Erfahrung zeigt, dass viele Opern und klassische Konzerte erst bei mehrmaligem H\u00f6ren ihre ganze Raffinesse entfalten. Die teils komplexen und langen Werke sollte man f\u00fcr den maximalen Erlebnisgenuss also vorab zumindest schon einmal geh\u00f6rt und gesehen haben und die Handlung in groben Z\u00fcgen kennen. Anders geht es zwar auch, mehr Spa\u00df macht es aber definitiv so.<\/p>\n<h2>So fr\u00fch wie m\u00f6glich buchen<\/h2>\n<p>Sowohl die Tickets als auch die Unterk\u00fcnfte sollte man so fr\u00fch wie m\u00f6glich fixieren. Das <a href=\"http:\/\/www.salzburgerfestspiele.at\/kontakt\/kartenbuero\" target=\"_blank\" rel=\"noopener noreferrer\">Kartenb\u00fcro<\/a> ist ganzj\u00e4hrig (au\u00dfer von 1. September bis Mitte Oktober) erreichbar.\u00a0Die Altstadt selbst ist Monate im Vorhinein bereits ausgebucht. Wer auf die Hotels und Unterk\u00fcnfte im umliegenden SalzburgerLand ausweicht, hat es definitiv billiger und stressfreier. Kurzentschlossene finden t\u00e4glich im Internet eine Restkartenliste auf der <a href=\"http:\/\/www.salzburgerfestspiele.at\/\" target=\"_blank\" rel=\"noopener noreferrer\">Seite der Festspiele<\/a>.<\/p>\n<h2>Anreise und Parkplatz<\/h2>\n<p>So sch\u00f6n die Stadt Salzburg \u00fcber die Jahrhunderte geworden ist, und so gut ihre strategische Lage zwischen Bergen und Fluss war: Gerade in der Festspielzeit hat man es als Autofahrer schwer. Wer mit dem eigenen PKW zu den Konzerten anreist, kommt am unkompliziertesten \u00fcber die Ausfahrt Salzburg-Mitte und die Neutorstra\u00dfe in die <a href=\"http:\/\/www.salzburg.info\/de\/service\/infos\/altstadtgaragen_az-256162\" target=\"_blank\" rel=\"noopener noreferrer\">Garagen im Berg<\/a>. Eine gute M\u00f6glichkeit sind auch die Park &amp; Ride Parkpl\u00e4tze rund um die Stadt. F\u00fcr alle anderen gilt: Die \u00f6ffentlichen Verkehrsmittel (S-Bahn und Z\u00fcge bis zum Hauptbahnhof oder Busse bis in die Altstadt) sind definitiv die stressfreiere Wahl.<\/p>\n<h2>Wettercheck<\/h2>\n<p>Auch einen Blick aufs Wetter sollte man haben. Besonders wer Karten f\u00fcr den <a href=\"https:\/\/www.salzburgerland.com\/de\/geschichte-salzburger-festspiele\/\">Jedermann<\/a> hat, kann von dr\u00fcckender Hitze bis hin zu k\u00fchlen Temperaturen einiges erwischen. Bei Regen wird der Jedermann im Gro\u00dfen Festspielhaus gezeigt. Besonderer Tipp bei Sch\u00f6nwetter: Eine Stunde vor jeder Jedermann-Vorstellung am Domplatz kann man sich in der Franziskanergasse um Stehplatzkarten bem\u00fchen und wer Gl\u00fcck hat, sieht so auch kurzfristig eine der hochbegehrten Auff\u00fchrungen.<\/p>\n<p>Mit diesen Tipps d\u00fcrften Sie perfekt vorbereitet sein auf die Salzburger Festspiele sowie die Pfingstfestspiele und die Osterfestspiele. Wer den Festspielbesuch mit einer Stadterkundung\u00a0kombinieren will, der hat mit der <a href=\"https:\/\/www.salzburgerland.com\/de\/die-salzburgerland-card-eine-karte-fuer-den-ganzen-urlaub\/\">SalzburgerLand Card<\/a> Gl\u00fcck: In ihr ist auch ein 24-Stunden-Salzburg-Ticket f\u00fcr so ziemlich alle Attraktionen und \u00f6ffentlichen Verkehrsmittel der Mozartstadt enthalten. Sie k\u00f6nnen direkt online Ihre Karte f\u00fcr den Urlaub im SalzburgerLand vorbestellen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lesen und h\u00f6ren Sie sich ein Die Erfahrung zeigt, dass viele Opern und klassische Konzerte erst bei mehrmaligem H\u00f6ren ihre ganze Raffinesse entfalten. Die teils komplexen und langen Werke sollte man f\u00fcr den maximalen Erlebnisgenuss also vorab zumindest schon einmal geh\u00f6rt und gesehen haben und die Handlung in groben Z\u00fcgen kennen. Anders geht es zwar [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":84922,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wl_entities_gutenberg":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[1],"tags":[13455],"wl_entity_type":[11495],"class_list":["post-60224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-salzburger-festspiele","wl_entity_type-article"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Perfekt vorbereitet zu den Salzburger Festspielen<\/title>\n<meta name=\"description\" content=\"Karten gekauft? Unterkunft gebucht? Kleidung zurechtgelegt? Wenn nicht, dann hilft Ihnen unser Guide zur Vorbereitung auf die Salzburger Festspiele.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts\/60224\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perfekt vorbereitet auf die Salzburger Festspiele\" \/>\n<meta property=\"og:description\" content=\"Karten gekauft? Unterkunft gebucht? Kleidung zurechtgelegt? Wenn nicht, dann hilft Ihnen unser Guide zur Vorbereitung auf die Salzburger Festspiele.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts\/60224\" \/>\n<meta property=\"og:site_name\" content=\"SalzburgerLand.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/salzburgerland\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-30T11:10:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-10T04:40:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2016\/08\/sbg_festspiele_jedermann-auffuehrung-salzburg-2015_tsg-e1497885071965-1200x675.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael Schmuck\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Salzburgerland\" \/>\n<meta name=\"twitter:site\" content=\"@Salzburgerland\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael Schmuck\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/vorbereitung-salzburger-festspiele\\\/\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/vorbereitung-salzburger-festspiele\\\/\",\"name\":\"Perfekt vorbereitet zu den Salzburger Festspielen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/vorbereitung-salzburger-festspiele\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/vorbereitung-salzburger-festspiele\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/sbg_festspiele_jedermann-auffuehrung-salzburg-2015_tsg-e1497885071965.jpg\",\"datePublished\":\"2016-08-30T11:10:10+00:00\",\"dateModified\":\"2020-07-10T04:40:38+00:00\",\"description\":\"Karten gekauft? Unterkunft gebucht? Kleidung zurechtgelegt? Wenn nicht, dann hilft Ihnen unser Guide zur Vorbereitung auf die Salzburger Festspiele.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/vorbereitung-salzburger-festspiele\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/vorbereitung-salzburger-festspiele\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/vorbereitung-salzburger-festspiele\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/sbg_festspiele_jedermann-auffuehrung-salzburg-2015_tsg-e1497885071965.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/sbg_festspiele_jedermann-auffuehrung-salzburg-2015_tsg-e1497885071965.jpg\",\"width\":2000,\"height\":1185,\"caption\":\"\u00a9 Tourismus Salzburg GmbH, G.Breitegger - Jedermann Salzburg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/vorbereitung-salzburger-festspiele\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Salzburger Festspiele\",\"item\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/salzburger-festspiele\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perfekt vorbereitet auf die Salzburger Festspiele\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/\",\"name\":\"SalzburgerLand.com\",\"description\":\"Ihr Urlaub in Salzburg, \u00d6sterreich\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/#organization\",\"name\":\"SalzburgerLand Tourismus GmbH\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/salzburgerland-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/salzburgerland-logo.jpg\",\"width\":1920,\"height\":827,\"caption\":\"SalzburgerLand Tourismus GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/salzburgerland\\\/\",\"https:\\\/\\\/x.com\\\/Salzburgerland\",\"https:\\\/\\\/www.instagram.com\\\/salzburgerland\\\/\",\"http:\\\/\\\/dbpedia.org\\\/resource\\\/Salzburg_(state)\",\"http:\\\/\\\/wikidata.dbpedia.org\\\/resource\\\/Q43325\",\"http:\\\/\\\/open.salzburgerland.com\\\/de\\\/entity\\\/salzburgerland\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/salzburgerland\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/#\\\/schema\\\/person\\\/a872a3566b5ef414265e74ee709dff17\",\"name\":\"Michael Schmuck\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/467abb9ff1229207f2510ec92856c4017e72c6ea446c65e62b83d59faf96e085?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/467abb9ff1229207f2510ec92856c4017e72c6ea446c65e62b83d59faf96e085?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/467abb9ff1229207f2510ec92856c4017e72c6ea446c65e62b83d59faf96e085?s=96&d=mm&r=g\",\"caption\":\"Michael Schmuck\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Perfekt vorbereitet zu den Salzburger Festspielen","description":"Karten gekauft? Unterkunft gebucht? Kleidung zurechtgelegt? Wenn nicht, dann hilft Ihnen unser Guide zur Vorbereitung auf die Salzburger Festspiele.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts\/60224","og_locale":"de_DE","og_type":"article","og_title":"Perfekt vorbereitet auf die Salzburger Festspiele","og_description":"Karten gekauft? Unterkunft gebucht? Kleidung zurechtgelegt? Wenn nicht, dann hilft Ihnen unser Guide zur Vorbereitung auf die Salzburger Festspiele.","og_url":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts\/60224","og_site_name":"SalzburgerLand.com","article_publisher":"https:\/\/www.facebook.com\/salzburgerland\/","article_published_time":"2016-08-30T11:10:10+00:00","article_modified_time":"2020-07-10T04:40:38+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2016\/08\/sbg_festspiele_jedermann-auffuehrung-salzburg-2015_tsg-e1497885071965-1200x675.jpg","type":"image\/jpeg"}],"author":"Michael Schmuck","twitter_card":"summary_large_image","twitter_creator":"@Salzburgerland","twitter_site":"@Salzburgerland","twitter_misc":{"Verfasst von":"Michael Schmuck","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.salzburgerland.com\/de\/vorbereitung-salzburger-festspiele\/","url":"https:\/\/www.salzburgerland.com\/de\/vorbereitung-salzburger-festspiele\/","name":"Perfekt vorbereitet zu den Salzburger Festspielen","isPartOf":{"@id":"https:\/\/www.salzburgerland.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salzburgerland.com\/de\/vorbereitung-salzburger-festspiele\/#primaryimage"},"image":{"@id":"https:\/\/www.salzburgerland.com\/de\/vorbereitung-salzburger-festspiele\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2016\/08\/sbg_festspiele_jedermann-auffuehrung-salzburg-2015_tsg-e1497885071965.jpg","datePublished":"2016-08-30T11:10:10+00:00","dateModified":"2020-07-10T04:40:38+00:00","description":"Karten gekauft? Unterkunft gebucht? Kleidung zurechtgelegt? Wenn nicht, dann hilft Ihnen unser Guide zur Vorbereitung auf die Salzburger Festspiele.","breadcrumb":{"@id":"https:\/\/www.salzburgerland.com\/de\/vorbereitung-salzburger-festspiele\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salzburgerland.com\/de\/vorbereitung-salzburger-festspiele\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salzburgerland.com\/de\/vorbereitung-salzburger-festspiele\/#primaryimage","url":"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2016\/08\/sbg_festspiele_jedermann-auffuehrung-salzburg-2015_tsg-e1497885071965.jpg","contentUrl":"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2016\/08\/sbg_festspiele_jedermann-auffuehrung-salzburg-2015_tsg-e1497885071965.jpg","width":2000,"height":1185,"caption":"\u00a9 Tourismus Salzburg GmbH, G.Breitegger - Jedermann Salzburg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salzburgerland.com\/de\/vorbereitung-salzburger-festspiele\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Salzburger Festspiele","item":"https:\/\/www.salzburgerland.com\/de\/salzburger-festspiele\/"},{"@type":"ListItem","position":2,"name":"Perfekt vorbereitet auf die Salzburger Festspiele"}]},{"@type":"WebSite","@id":"https:\/\/www.salzburgerland.com\/de\/#website","url":"https:\/\/www.salzburgerland.com\/de\/","name":"SalzburgerLand.com","description":"Ihr Urlaub in Salzburg, \u00d6sterreich","publisher":{"@id":"https:\/\/www.salzburgerland.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salzburgerland.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.salzburgerland.com\/de\/#organization","name":"SalzburgerLand Tourismus GmbH","url":"https:\/\/www.salzburgerland.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salzburgerland.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/01\/salzburgerland-logo.jpg","contentUrl":"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/01\/salzburgerland-logo.jpg","width":1920,"height":827,"caption":"SalzburgerLand Tourismus GmbH"},"image":{"@id":"https:\/\/www.salzburgerland.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/salzburgerland\/","https:\/\/x.com\/Salzburgerland","https:\/\/www.instagram.com\/salzburgerland\/","http:\/\/dbpedia.org\/resource\/Salzburg_(state)","http:\/\/wikidata.dbpedia.org\/resource\/Q43325","http:\/\/open.salzburgerland.com\/de\/entity\/salzburgerland","https:\/\/www.youtube.com\/user\/salzburgerland"]},{"@type":"Person","@id":"https:\/\/www.salzburgerland.com\/de\/#\/schema\/person\/a872a3566b5ef414265e74ee709dff17","name":"Michael Schmuck","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/467abb9ff1229207f2510ec92856c4017e72c6ea446c65e62b83d59faf96e085?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/467abb9ff1229207f2510ec92856c4017e72c6ea446c65e62b83d59faf96e085?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/467abb9ff1229207f2510ec92856c4017e72c6ea446c65e62b83d59faf96e085?s=96&d=mm&r=g","caption":"Michael Schmuck"}}]}},"_wl_alt_label":[],"wl:entity_url":"http:\/\/open.salzburgerland.com\/de\/post\/die_perfekte_vorbereitung_auf_die_salzburger_festspiele","_links":{"self":[{"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts\/60224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/comments?post=60224"}],"version-history":[{"count":0,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts\/60224\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/media\/84922"}],"wp:attachment":[{"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/media?parent=60224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/categories?post=60224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/tags?post=60224"},{"taxonomy":"wl_entity_type","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/wl_entity_type?post=60224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}