{"id":598346,"date":"2021-07-29T17:31:19","date_gmt":"2021-07-29T15:31:19","guid":{"rendered":"https:\/\/www.salzburgerland.com\/de\/?p=598346"},"modified":"2021-08-02T11:20:24","modified_gmt":"2021-08-02T09:20:24","slug":"reiseleiterin-sonja-im-portrait","status":"publish","type":"post","link":"https:\/\/www.salzburgerland.com\/de\/reiseleiterin-sonja-im-portrait\/","title":{"rendered":"Reiseleiterin Sonja"},"content":{"rendered":"<h2>Einmal Tourismus, immer Tourismus<\/h2>\n<p>Sonja ist bei weitem kein Branchen-Neuling. Bereits w\u00e4hrend ihrer Zeit in der Tourismusschule sammelte sie erste Erfahrungen im Umgang mit G\u00e4sten. Nach der Ausbildung und einem l\u00e4ngeren Auslandsaufenthalt zog es die Ober\u00f6sterreicherin in die Stadt Salzburg. Dort arbeitet sie mittlerweile bereits seit mehr als einem Jahrzehnt als Reiseleitern. Was ihr daran besonders gut gef\u00e4llt?<\/p>\n<blockquote><p>F\u00fcr mich ist es erf\u00fcllend, den Urlaub der G\u00e4ste noch sch\u00f6ner zu machen, den Teilnehmer:innen meiner Bustouren Wissen zu vermitteln. Das SalzburgerLand herzuzeigen und individuell auf die Interessen der Leute einzugehen, sie in gewisser Weise auch kennenzulernen \u2013 das macht mir Freude.<\/p><\/blockquote>\n<h2>Reiseleiterin aus Leidenschaft<\/h2>\n<p>Was geh\u00f6rt eigentlich alles zum Beruf der Reiseleiterin dazu? Mehr, als man vielleicht im ersten Moment denkt, wie uns Sonja erkl\u00e4rt: \u201eAls erstes hole ich das Auto. Ich bin unter anderem f\u00fcr das S\u00e4ubern \u2013 und in letzter Zeit insbesondere auch f\u00fcr das Desinfizieren \u2013 zust\u00e4ndig. Entweder steigen die G\u00e4ste bei uns ein, oder ich hole sie bei ihrem Hotel ab. Nach der Begr\u00fc\u00dfung startet die jeweilige Tour. Und am Ende des Tages gilt: Sind meine G\u00e4ste gl\u00fccklich, bin ich es auch. Dann kann ich am Abend zufrieden heimgehen.\u201c<\/p>\n<img decoding=\"async\" class=\"size-1170_658 wp-image-600666\" src=\"https:\/\/cdn.salzburgerland.com\/de\/wp-content\/uploads\/2021\/07\/0j3a4826-1170x658.jpg\" alt=\"\" width=\"1170\" height=\"658\" srcset=\"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2021\/07\/0j3a4826-1170x658.jpg 1170w, https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2021\/07\/0j3a4826-1200x675.jpg 1200w\" sizes=\"(max-width: 1170px) 100vw, 1170px\">\n<p>\u00a0<\/p>\n<p>Interessant: Salzburg Panorama Tours bietet etwa zehn Bustouren an, die man dann kombinieren kann. Zudem gibt es jederzeit die M\u00f6glichkeit, Privattouren zu buchen \u2013 zum Beispiel nach Hallstatt\u00a0oder zum Gro\u00dfglockner. Wer Reiseleiter:in werden will, muss selbstverst\u00e4ndlich Autofahren k\u00f6nnen, \u00fcber perfekte Englischkenntnisse verf\u00fcgen und mindestens eine weitere Sprache beherrschen. Sonja bietet zum Beispiel Touren auf Deutsch, Englisch und Spanisch an und gibt zu bedenken: \u201eGleichzeitig reden und fahren ist nicht jedermanns Sache.\u201c<\/p>\n<p><strong>Apropos Touren:<\/strong> Wir sind neugierig und wollen wissen, ob Sonja eine Lieblingstour hat. \u201eGrunds\u00e4tzlich sollten wir alle Touren fahren k\u00f6nnen. Ich find es am sch\u00f6nsten, wenn die Leute mitgehen, Fragen stellen und die Fahrt dadurch interaktiv wird. Da spielt es f\u00fcr mich keine Rolle, ob es die Sound-of-Music-Tour oder die City-Tour ist.\u201c<\/p>\n<h2>In Krisenzeiten erfinderisch werden<\/h2>\n<p>W\u00e4hrend der Pandemie fehlte der Urlaubsgast, weshalb Sonja die meiste Zeit zu Hause geblieben ist. Das Kundenklientel konnte nicht reisen, was dazu f\u00fchrte, dass sie praktisch arbeitslos war. Als die Ma\u00dfnahmen gelockert wurden, fuhr sie wieder ab und zu Touren, es gab aber nach wie vor sehr wenig zu tun.<\/p>\n<img decoding=\"async\" class=\"size-1170_658 wp-image-600673\" src=\"https:\/\/cdn.salzburgerland.com\/de\/wp-content\/uploads\/2021\/07\/0j3a4878-1-1170x658.jpg\" alt=\"\" width=\"1170\" height=\"658\" srcset=\"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2021\/07\/0j3a4878-1-1170x658.jpg 1170w, https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2021\/07\/0j3a4878-1-1200x675.jpg 1200w\" sizes=\"(max-width: 1170px) 100vw, 1170px\">\n<p>\u00a0<\/p>\n<p>Also musste sie sich nach einer Alternative umsehen: \u201eIch habe angefangen, in Covid-Teststationen zu arbeiten und damit quasi eine ganz andere Branche f\u00fcr mich entdeckt. Uns im Tourismus hat es einfach sehr hart getroffen. Da musste ich mich zumindest vor\u00fcbergehend beruflich umorientieren.\u201c<\/p>\n<h2>Von sch\u00f6nen und weniger sch\u00f6nen Momenten<\/h2>\n<p>Von sch\u00f6nen Momenten zu berichten, f\u00e4llt Sonja leicht: \u201eDa gibt es mehrere. Besonders sch\u00f6n ist es immer, wenn Kinder zum Beispiel bei der Sound-of-Music-Tour mitmachen. Sehr junge M\u00e4dchen k\u00f6nnen teilweise ganz allein die Lieder singen. Das finde ich total toll. Oder wenn auch k\u00f6rperlich beeintr\u00e4chtige G\u00e4ste durch meine Touren die Region besser kennenlernen k\u00f6nnen.\u201c<\/p>\n<p>Jede Medaille hat zwei Seiten \u2013 und so passiert auch in Sonjas Alltag nicht immer nur Positives. Vor allem der Autoverkehr bringt so seine T\u00fccken mit sich: \u201eEs kann immer sein, dass man irgendwo einen Unfall hat, weil man zum Beispiel unterwegs geschnitten wird. Zum Gl\u00fcck ist meinen G\u00e4sten und mir nie etwas Schlimmes passiert.\u201c Etwas risiko\u00e4rmer, aber ebenfalls \u00e4rgerlich: wenn sich G\u00e4ste auf ihren Touren langweilen. Das ist aber eher der Ausnahmefall, wie sie uns versichert.<\/p>\n<img decoding=\"async\" class=\"size-1170_658 wp-image-600669\" src=\"https:\/\/cdn.salzburgerland.com\/de\/wp-content\/uploads\/2021\/07\/0j3a4978-1170x658.jpg\" alt=\"\" width=\"1170\" height=\"658\" srcset=\"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2021\/07\/0j3a4978-1170x658.jpg 1170w, https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2021\/07\/0j3a4978-1200x675.jpg 1200w\" sizes=\"(max-width: 1170px) 100vw, 1170px\">\n<p>\u00a0<\/p>\n<h2>Blick in Richtung Zukunft<\/h2>\n<p>Wir fragen Sonja, was sie sich f\u00fcr den Sommer im SalzburgerLand w\u00fcnscht. Sie hofft, dass in den kommenden Monaten Tourismus stattfinden kann und dass es vielen G\u00e4sten m\u00f6glich sein wird, die Region zu besuchen. Wie geht es f\u00fcr sie die n\u00e4chsten Jahre beruflich weiter? Plant sie, auch weiterhin als Reiseleiterin zu arbeiten?<\/p>\n<blockquote><p>Reiseleitung ist mittlerweile auch ein Hobby von mir, dem ich sehr gerne weiter nachgehen werde. Solange es mir Spa\u00df macht, nat\u00fcrlich. Denn ich bin davon \u00fcberzeugt, dass man diesen Job nicht machen kann, ohne Freude daran zu haben.<\/p><\/blockquote>\n<h2>SalzburgerLand \u2013 ein Genuss f\u00fcr jedermann<\/h2>\n<p>Sonja lebt im Salzkammergut und hat damit auch schon seit jeher eine besondere Beziehung zum SalzburgerLand. Sie erz\u00e4hlt uns, was diese Region ihrer Meinung nach auszeichnet: \u201eDie Natur und die Leute sind das, was die Region ausmacht. Sicher tragen auch die Kulinarik und das Brauchtum ihren Teil zum besonderen Charme bei.\u201c In diesem Zusammenhang ist es ihr au\u00dferdem wichtig, zu betonen:<\/p>\n<blockquote><p>Nicht nur G\u00e4ste, sondern auch die Leute, die hier leben, sollten das SalzburgerLand genie\u00dfen k\u00f6nnen. Mir ist es ein Anliegen, auch Einheimischen bewusst zu machen, was sie an ihrer Region haben. Ich bin einfach der Meinung, es ist wundersch\u00f6n hier. Wir k\u00f6nnen wirklich froh sein, im und f\u00fcr das SalzburgerLand zu leben.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Einmal Tourismus, immer Tourismus Sonja ist bei weitem kein Branchen-Neuling. Bereits w\u00e4hrend ihrer Zeit in der Tourismusschule sammelte sie erste Erfahrungen im Umgang mit G\u00e4sten. Nach der Ausbildung und einem l\u00e4ngeren Auslandsaufenthalt zog es die Ober\u00f6sterreicherin in die Stadt Salzburg. Dort arbeitet sie mittlerweile bereits seit mehr als einem Jahrzehnt als Reiseleitern. Was ihr daran [&hellip;]<\/p>\n","protected":false},"author":95,"featured_media":600671,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wl_entities_gutenberg":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[1],"tags":[],"wl_entity_type":[11495],"class_list":["post-598346","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","wl_entity_type-article"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Reiseleiterin Sonja im Portrait | SalzburgerLand Tourismus<\/title>\n<meta name=\"description\" content=\"Einmal Tourismus, immer Tourismus: Reiseleiterin Sonja begleitet seit \u00fcber zehn Jahren Urlaubsg\u00e4ste im SalzburgerLand. Zum Lebens(t)raum!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts\/598346\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reiseleiterin Sonja\" \/>\n<meta property=\"og:description\" content=\"Einmal Tourismus, immer Tourismus: Reiseleiterin Sonja begleitet seit \u00fcber zehn Jahren Urlaubsg\u00e4ste im SalzburgerLand. Zum Lebens(t)raum!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts\/598346\" \/>\n<meta property=\"og:site_name\" content=\"SalzburgerLand.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/salzburgerland\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-29T15:31:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-02T09:20:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2021\/07\/0j3a4933-1-1200x675.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Katharina Wohlfahrt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Salzburgerland\" \/>\n<meta name=\"twitter:site\" content=\"@Salzburgerland\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Katharina Wohlfahrt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/reiseleiterin-sonja-im-portrait\\\/\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/reiseleiterin-sonja-im-portrait\\\/\",\"name\":\"Reiseleiterin Sonja im Portrait | SalzburgerLand Tourismus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/reiseleiterin-sonja-im-portrait\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/reiseleiterin-sonja-im-portrait\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/0j3a4933-1-scaled.jpg\",\"datePublished\":\"2021-07-29T15:31:19+00:00\",\"dateModified\":\"2021-08-02T09:20:24+00:00\",\"description\":\"Einmal Tourismus, immer Tourismus: Reiseleiterin Sonja begleitet seit \u00fcber zehn Jahren Urlaubsg\u00e4ste im SalzburgerLand. Zum Lebens(t)raum!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/reiseleiterin-sonja-im-portrait\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/reiseleiterin-sonja-im-portrait\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/reiseleiterin-sonja-im-portrait\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/0j3a4933-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/0j3a4933-1-scaled.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"Eine Frau in einer gemusterten Bluse betritt ein Geb\u00e4ude und l\u00e4chelt, w\u00e4hrend sie auf einem Weg mit gelben Geb\u00e4uden steht.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/reiseleiterin-sonja-im-portrait\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Lebens(t)r\u00e4ume\",\"item\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/lebenstraeume\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reiseleiterin Sonja\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/\",\"name\":\"SalzburgerLand.com\",\"description\":\"Ihr Urlaub in Salzburg, \u00d6sterreich\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/#organization\",\"name\":\"SalzburgerLand Tourismus GmbH\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/salzburgerland-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/salzburgerland-logo.jpg\",\"width\":1920,\"height\":827,\"caption\":\"SalzburgerLand Tourismus GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/salzburgerland\\\/\",\"https:\\\/\\\/x.com\\\/Salzburgerland\",\"https:\\\/\\\/www.instagram.com\\\/salzburgerland\\\/\",\"http:\\\/\\\/dbpedia.org\\\/resource\\\/Salzburg_(state)\",\"http:\\\/\\\/wikidata.dbpedia.org\\\/resource\\\/Q43325\",\"http:\\\/\\\/open.salzburgerland.com\\\/de\\\/entity\\\/salzburgerland\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/salzburgerland\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/#\\\/schema\\\/person\\\/cde8c8d045c58df7c7c1b05eb14774f1\",\"name\":\"Katharina Wohlfahrt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3a09097c536e3805e74e46a9b8515e6c1f5d97d236ec0fdb91533f3c7834d459?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3a09097c536e3805e74e46a9b8515e6c1f5d97d236ec0fdb91533f3c7834d459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3a09097c536e3805e74e46a9b8515e6c1f5d97d236ec0fdb91533f3c7834d459?s=96&d=mm&r=g\",\"caption\":\"Katharina Wohlfahrt\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Reiseleiterin Sonja im Portrait | SalzburgerLand Tourismus","description":"Einmal Tourismus, immer Tourismus: Reiseleiterin Sonja begleitet seit \u00fcber zehn Jahren Urlaubsg\u00e4ste im SalzburgerLand. Zum Lebens(t)raum!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts\/598346","og_locale":"de_DE","og_type":"article","og_title":"Reiseleiterin Sonja","og_description":"Einmal Tourismus, immer Tourismus: Reiseleiterin Sonja begleitet seit \u00fcber zehn Jahren Urlaubsg\u00e4ste im SalzburgerLand. Zum Lebens(t)raum!","og_url":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts\/598346","og_site_name":"SalzburgerLand.com","article_publisher":"https:\/\/www.facebook.com\/salzburgerland\/","article_published_time":"2021-07-29T15:31:19+00:00","article_modified_time":"2021-08-02T09:20:24+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2021\/07\/0j3a4933-1-1200x675.jpg","type":"image\/jpeg"}],"author":"Katharina Wohlfahrt","twitter_card":"summary_large_image","twitter_creator":"@Salzburgerland","twitter_site":"@Salzburgerland","twitter_misc":{"Verfasst von":"Katharina Wohlfahrt","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.salzburgerland.com\/de\/reiseleiterin-sonja-im-portrait\/","url":"https:\/\/www.salzburgerland.com\/de\/reiseleiterin-sonja-im-portrait\/","name":"Reiseleiterin Sonja im Portrait | SalzburgerLand Tourismus","isPartOf":{"@id":"https:\/\/www.salzburgerland.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salzburgerland.com\/de\/reiseleiterin-sonja-im-portrait\/#primaryimage"},"image":{"@id":"https:\/\/www.salzburgerland.com\/de\/reiseleiterin-sonja-im-portrait\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2021\/07\/0j3a4933-1-scaled.jpg","datePublished":"2021-07-29T15:31:19+00:00","dateModified":"2021-08-02T09:20:24+00:00","description":"Einmal Tourismus, immer Tourismus: Reiseleiterin Sonja begleitet seit \u00fcber zehn Jahren Urlaubsg\u00e4ste im SalzburgerLand. Zum Lebens(t)raum!","breadcrumb":{"@id":"https:\/\/www.salzburgerland.com\/de\/reiseleiterin-sonja-im-portrait\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salzburgerland.com\/de\/reiseleiterin-sonja-im-portrait\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salzburgerland.com\/de\/reiseleiterin-sonja-im-portrait\/#primaryimage","url":"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2021\/07\/0j3a4933-1-scaled.jpg","contentUrl":"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2021\/07\/0j3a4933-1-scaled.jpg","width":1920,"height":1280,"caption":"Eine Frau in einer gemusterten Bluse betritt ein Geb\u00e4ude und l\u00e4chelt, w\u00e4hrend sie auf einem Weg mit gelben Geb\u00e4uden steht."},{"@type":"BreadcrumbList","@id":"https:\/\/www.salzburgerland.com\/de\/reiseleiterin-sonja-im-portrait\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Lebens(t)r\u00e4ume","item":"https:\/\/www.salzburgerland.com\/de\/lebenstraeume\/"},{"@type":"ListItem","position":2,"name":"Reiseleiterin Sonja"}]},{"@type":"WebSite","@id":"https:\/\/www.salzburgerland.com\/de\/#website","url":"https:\/\/www.salzburgerland.com\/de\/","name":"SalzburgerLand.com","description":"Ihr Urlaub in Salzburg, \u00d6sterreich","publisher":{"@id":"https:\/\/www.salzburgerland.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salzburgerland.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.salzburgerland.com\/de\/#organization","name":"SalzburgerLand Tourismus GmbH","url":"https:\/\/www.salzburgerland.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salzburgerland.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/01\/salzburgerland-logo.jpg","contentUrl":"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/01\/salzburgerland-logo.jpg","width":1920,"height":827,"caption":"SalzburgerLand Tourismus GmbH"},"image":{"@id":"https:\/\/www.salzburgerland.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/salzburgerland\/","https:\/\/x.com\/Salzburgerland","https:\/\/www.instagram.com\/salzburgerland\/","http:\/\/dbpedia.org\/resource\/Salzburg_(state)","http:\/\/wikidata.dbpedia.org\/resource\/Q43325","http:\/\/open.salzburgerland.com\/de\/entity\/salzburgerland","https:\/\/www.youtube.com\/user\/salzburgerland"]},{"@type":"Person","@id":"https:\/\/www.salzburgerland.com\/de\/#\/schema\/person\/cde8c8d045c58df7c7c1b05eb14774f1","name":"Katharina Wohlfahrt","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/3a09097c536e3805e74e46a9b8515e6c1f5d97d236ec0fdb91533f3c7834d459?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3a09097c536e3805e74e46a9b8515e6c1f5d97d236ec0fdb91533f3c7834d459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3a09097c536e3805e74e46a9b8515e6c1f5d97d236ec0fdb91533f3c7834d459?s=96&d=mm&r=g","caption":"Katharina Wohlfahrt"}}]}},"_wl_alt_label":[],"wl:entity_url":"http:\/\/open.salzburgerland.com\/de\/post\/kochlehrling_christian_im_portrait","_links":{"self":[{"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts\/598346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/users\/95"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/comments?post=598346"}],"version-history":[{"count":5,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts\/598346\/revisions"}],"predecessor-version":[{"id":601469,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts\/598346\/revisions\/601469"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/media\/600671"}],"wp:attachment":[{"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/media?parent=598346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/categories?post=598346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/tags?post=598346"},{"taxonomy":"wl_entity_type","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/wl_entity_type?post=598346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}