{"id":155231,"date":"2017-06-27T14:51:22","date_gmt":"2017-06-27T12:51:22","guid":{"rendered":"https:\/\/www.salzburgerland.com\/de\/?p=155231"},"modified":"2025-10-06T14:22:29","modified_gmt":"2025-10-06T12:22:29","slug":"gastein-nina-zwischen-nostalgie-und-moderne","status":"publish","type":"post","link":"https:\/\/www.salzburgerland.com\/de\/gastein-nina-zwischen-nostalgie-und-moderne\/","title":{"rendered":"GASTEIN: Nina zwischen Nostalgie und Moderne"},"content":{"rendered":"<p><span>Seit 2011 h\u00e4lt sie ihre Leser \u00fcber alles, was sie mag, am Laufenden. Damals war <\/span><span>der<\/span><span> Blog <a href=\"https:\/\/www.salzburgerland.com\/de\/berries-passion\/\" target=\"_blank\" rel=\"noopener noreferrer\">Berries &amp; Passion<\/a> nur als Spielwiese f\u00fcr die sch\u00f6nen Dinge im Leben gedacht, heute z\u00e4hlt er zu den erfolgreichsten in \u00d6sterreich. Und Nina? Sie ist eine Urwienerin. Und schreibt von dort aus \u00fcber ihr Leben und ihre Reisen \u2013 auch au\u00dferhalb der Hauptstadt. An drei sonnigen Wintertagen ging ihre Reise dieses Mal in die Berge \u2013 und zwar ins <a class=\"wl-entity-page-link\" title=\"Gasteiner Tal\" href=\"https:\/\/www.salzburgerland.com\/de\/gasteinertal\/\" data-id=\"https:\/\/open.salzburgerland.com\/de\/entity\/gasteinertal\">Gasteinertal<\/a>.\u00a0Mit dabei: ihr Hund Tobi!<\/span><\/p>\n<p><iframe title=\"Berries and Passion im SalzburgerLand\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/CCFRhseL8RI?feature=oembed&amp;rel=0&amp;modestbranding=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<h2>Ninas Geheimtipps im Gasteinertal: zweimal Gipfel, einmal Tal<\/h2>\n<p><span>Fr\u00fchst\u00fcck ist die wichtigste Mahlzeit des Tages, auch f\u00fcr Blogger. Um den Weitblick \u00fcbers Gasteinertal zu erhalten, ging es f\u00fcr Nina in luftige H\u00f6hen auf den Kreuzkogel. Nach einer rund zwanzigmin\u00fctigen Fahrt in der Gondel kam es zu einer kurzen Irritation: Von einem Restaurant fehlte jede Spur. Wie Nina gleich herausgefunden hatte, war das auch gut so: Das <a href=\"https:\/\/www.gastein.com\/gastein\/kulinarik\/gipfelfruehstueck\/\">Gipfelfr\u00fchst\u00fcck<\/a> wurde in einer ehemaligen Wetterstation serviert. Der Vorteil? Die kugelf\u00f6rmige Architektur erlaubte einen 360\u00b0-Ausblick auf die umliegenden Berge. Atemberaubend. Und g\u2019schmackig!<\/span><\/p>\n\n\t\t\t<div id=\"155231-1\" class=\"gallery gallery-155231 gallery-columns-3 gallery-size-medium\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n\t\t\t\t<ul class=\"gallery-row gallery-col-3 gallery-clear\">\n\t\t\t\t\t<li class=\"gallery-item col-3\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\">\n\t\t\t\t\t\t<div class=\"gallery-icon landscape\"><a href=\"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/wetterstation_berries-and-passion-1920x1067.jpg\" title=\"Wetterstation_Berries and Passion\"><img decoding=\"async\" data-title=\"\u00a9 SalzburgerLand Tourismus, Jonathan Forsthuber \u2013 Gipfelfr\u00fchst\u00fcck\" title=\"\u00a9 SalzburgerLand Tourismus, Jonathan Forsthuber \u2013 Gipfelfr\u00fchst\u00fcck\" data-caption=\"\u00a9 SalzburgerLand Tourismus, Jonathan Forsthuber \u2013 Gipfelfr\u00fchst\u00fcck\" width=\"1024\" height=\"569\" src=\"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/wetterstation_berries-and-passion-1024x569.jpg\" class=\"attachment-medium size-medium\" alt=\"Wetterstation f\u00fcrs Gipfelfr\u00fchst\u00fcck am Kreuzkogel (vergr\u00f6\u00dferte Ansicht)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/wetterstation_berries-and-passion-1024x569.jpg 1024w, https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/wetterstation_berries-and-passion-370x206.jpg 370w, https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/wetterstation_berries-and-passion-1920x1067.jpg 1920w, https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/wetterstation_berries-and-passion-270x150.jpg 270w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" aria-describedby=\"figcaption-155231-155261\" itemprop=\"thumbnail\"><\/a><\/div>\n\t\t\t\t\t\t<span id=\"figcaption-155231-155261\" class=\"gallery-caption\" itemprop=\"caption\"><span aria-hidden=\"true\">\u00a9 SalzburgerLand Tourismus, Jonathan Forsthuber \u2013 Gipfelfr\u00fchst\u00fcck<\/span><\/span>\n\t\t\t\t\t<\/li>\n\t\t\t\t\t<li class=\"gallery-item col-3\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\">\n\t\t\t\t\t\t<div class=\"gallery-icon landscape\"><a href=\"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/in-der-wetterstation_gipfelfruehstueck_kreuzkogel-1920x1067.jpg\" title=\"In der Wetterstation_Gipfelfruehstueck_Kreuzkogel\"><img decoding=\"async\" data-title=\"\u00a9 SalzburgerLand Tourismus, Jonathan Forsthuber \u2013 Gipfelfr\u00fchst\u00fcck in Gastein\" title=\"\u00a9 SalzburgerLand Tourismus, Jonathan Forsthuber \u2013 Gipfelfr\u00fchst\u00fcck in Gastein\" data-caption=\"\u00a9 SalzburgerLand Tourismus, Jonathan Forsthuber \u2013 Gipfelfr\u00fchst\u00fcck in Gastein\" width=\"1024\" height=\"569\" src=\"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/in-der-wetterstation_gipfelfruehstueck_kreuzkogel-1024x569.jpg\" class=\"attachment-medium size-medium\" alt=\"Gipfelfr\u00fchst\u00fcck am Kreuzkogel im Gasteinertal (vergr\u00f6\u00dferte Ansicht)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/in-der-wetterstation_gipfelfruehstueck_kreuzkogel-1024x569.jpg 1024w, https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/in-der-wetterstation_gipfelfruehstueck_kreuzkogel-370x206.jpg 370w, https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/in-der-wetterstation_gipfelfruehstueck_kreuzkogel-1920x1067.jpg 1920w, https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/in-der-wetterstation_gipfelfruehstueck_kreuzkogel-270x150.jpg 270w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" aria-describedby=\"figcaption-155231-155264\" itemprop=\"thumbnail\"><\/a><\/div>\n\t\t\t\t\t\t<span id=\"figcaption-155231-155264\" class=\"gallery-caption\" itemprop=\"caption\"><span aria-hidden=\"true\">\u00a9 SalzburgerLand Tourismus, Jonathan Forsthuber \u2013 Gipfelfr\u00fchst\u00fcck in Gastein<\/span><\/span>\n\t\t\t\t\t<\/li>\n\t\t\t\t\t<li class=\"gallery-item col-3\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\">\n\t\t\t\t\t\t<div class=\"gallery-icon landscape\"><a href=\"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/nina-radman-beim-gipfelfruhstuck-am-kreuzkogel-im-gasteinertal-1920x1067.jpg\" title=\"Nina Radman beim Gipfelfru\u0308hstu\u0308ck am Kreuzkogel im Gasteinertal\"><img decoding=\"async\" data-title=\"\u00a9 SalzburgerLand Tourismus - Gipfelfr\u00fchst\u00fcck in Gastein\" title=\"\u00a9 SalzburgerLand Tourismus - Gipfelfr\u00fchst\u00fcck in Gastein\" data-caption=\"\u00a9 SalzburgerLand Tourismus - Gipfelfr\u00fchst\u00fcck in Gastein\" width=\"1024\" height=\"569\" src=\"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/nina-radman-beim-gipfelfruhstuck-am-kreuzkogel-im-gasteinertal-1024x569.jpg\" class=\"attachment-medium size-medium\" alt=\"Nina Radman beim Gipfelfru\u0308hstu\u0308ck am Kreuzkogel im Gasteinertal (vergr\u00f6\u00dferte Ansicht)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/nina-radman-beim-gipfelfruhstuck-am-kreuzkogel-im-gasteinertal-1024x569.jpg 1024w, https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/nina-radman-beim-gipfelfruhstuck-am-kreuzkogel-im-gasteinertal-370x206.jpg 370w, https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/nina-radman-beim-gipfelfruhstuck-am-kreuzkogel-im-gasteinertal-1920x1067.jpg 1920w, https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/nina-radman-beim-gipfelfruhstuck-am-kreuzkogel-im-gasteinertal-270x150.jpg 270w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" aria-describedby=\"figcaption-155231-155266\" itemprop=\"thumbnail\"><\/a><\/div>\n\t\t\t\t\t\t<span id=\"figcaption-155231-155266\" class=\"gallery-caption\" itemprop=\"caption\"><span aria-hidden=\"true\">\u00a9 SalzburgerLand Tourismus \u2013 Gipfelfr\u00fchst\u00fcck in Gastein<\/span><\/span>\n\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t<\/div><!-- .gallery -->\n\n<h2>Alles Gl\u00fcck dieser Erde liegt auf dem R\u00fccken der \u2026 Huskies.<\/h2>\n<p><span>Nina liebt Hunde. Was liegt also n\u00e4her, als auf einen Hundeschlitten zu h\u00fcpfen und eine Runde mit Huskies zu drehen? F\u00fcr Nina war die <a href=\"https:\/\/www.gastein.com\/aktiv\/winter\/winter-mehr\/husky-erlebnis\/\" target=\"_blank\" rel=\"noopener noreferrer\">Schlittenfahrt mit den Vierbeinern<\/a> eine Premiere: \u201eHundeschlitten zu fahren ist ein Kindheitstraum von mir. Ich wollte das immer schon mal machen, bin aber bis jetzt noch nie dazugekommen.\u201c Das Fazit nach gleich einigen Runden mit den Huskies? \u201eIch habe total untersch\u00e4tzt, wie schnell die Hunde laufen. Es war auf jeden Fall mein absolutes Highlight.\u201c<\/span><\/p>\n<div id=\"attachment_155540\" style=\"width: 1180px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-155540\" class=\"size-1170_658 wp-image-155540\" src=\"https:\/\/cdn.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/nina-radman_huskys-1170x658.jpg\" alt=\"\" width=\"1170\" height=\"658\" srcset=\"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/nina-radman_huskys-1170x658.jpg 1170w, https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/nina-radman_huskys-768x432.jpg 768w, https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/nina-radman_huskys.jpg 1920w\" sizes=\"(max-width: 1170px) 100vw, 1170px\"><p id=\"caption-attachment-155540\" class=\"wp-caption-text\">\u00a9 SalzburgerLand Tourismus, Fr\u00e4ulein Floras Favourite Hangouts \u2013 Huskyschlittenfahrt<\/p><\/div>\n<h2>\u00dcber den Wolken<\/h2>\n<p><span>\u2026 oder zumindest fast: Am Stubnerkogel schwingt man auf der <a href=\"https:\/\/www.gastein.com\/service\/gastein-von-a-z\/detail\/infrastruktur\/haengebruecke-am-stubnerkogel-bad-gastein\/\" target=\"_blank\" rel=\"noopener noreferrer\">Panoramabr\u00fccke<\/a> \u00fcber einem atemberaubenden Tal. Rund 140 Meter f\u00fchrt sie von einem Ende zum anderen. Wagt man sich darauf, sollte man auf jeden Fall schwindelfrei sein: Die H\u00e4ngebr\u00fccke befindet sich n\u00e4mlich auf 2.300 Metern H\u00f6he. Fun Fact: Es ist die erste Br\u00fccke, die auf solcher H\u00f6he errichtet wurde. Inklusive Picture-Point f\u00fcrs Instagram-Album. Ein Traum f\u00fcr Blogger und Instagrammer.<\/span><\/p>\n<div id=\"attachment_156158\" style=\"width: 1180px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-156158\" class=\"size-1170_658 wp-image-156158\" src=\"https:\/\/cdn.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/berries-and-passion_fin-42-von-53-1170x658.jpg\" alt=\"Nina Radman auf H\u00e4ngebr\u00fccke\" width=\"1170\" height=\"658\" srcset=\"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/berries-and-passion_fin-42-von-53-1170x658.jpg 1170w, https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/berries-and-passion_fin-42-von-53-768x432.jpg 768w, https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/berries-and-passion_fin-42-von-53.jpg 1920w\" sizes=\"(max-width: 1170px) 100vw, 1170px\"><p id=\"caption-attachment-156158\" class=\"wp-caption-text\">\u00a9 SalzburgerLand Tourismus, Jonathan Forsthuber \u2013 Nina auf der H\u00e4ngebr\u00fccke<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Seit 2011 h\u00e4lt sie ihre Leser \u00fcber alles, was sie mag, am Laufenden. Damals war der Blog Berries &amp; Passion nur als Spielwiese f\u00fcr die sch\u00f6nen Dinge im Leben gedacht, heute z\u00e4hlt er zu den erfolgreichsten in \u00d6sterreich. Und Nina? Sie ist eine Urwienerin. Und schreibt von dort aus \u00fcber ihr Leben und ihre Reisen [&hellip;]<\/p>\n","protected":false},"author":57,"featured_media":155232,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wl_entities_gutenberg":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[1],"tags":[],"wl_entity_type":[11495],"class_list":["post-155231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","wl_entity_type-article"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>GASTEIN: Nina zwischen Nostalgie und Moderne \u00bb SalzburgerLand.com<\/title>\n<meta name=\"description\" content=\"Zu Besuch im Gasteinertal: Die Bloggerin Nina Radman aka Berries &amp; Passion hat das SalzburgerLand erkundet und teilt ihre Geheimtipps mit uns.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts\/155231\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GASTEIN: Nina zwischen Nostalgie und Moderne\" \/>\n<meta property=\"og:description\" content=\"Zu Besuch im Gasteinertal: Die Bloggerin Nina Radman aka Berries &amp; Passion hat das SalzburgerLand erkundet und teilt ihre Geheimtipps mit uns.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts\/155231\" \/>\n<meta property=\"og:site_name\" content=\"SalzburgerLand.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/salzburgerland\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-27T12:51:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-06T12:22:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/nina-radman-im-gasteinertal_titel-1200x675.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Miriam Kreiseder\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Salzburgerland\" \/>\n<meta name=\"twitter:site\" content=\"@Salzburgerland\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Miriam Kreiseder\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/gastein-nina-zwischen-nostalgie-und-moderne\\\/\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/gastein-nina-zwischen-nostalgie-und-moderne\\\/\",\"name\":\"GASTEIN: Nina zwischen Nostalgie und Moderne \u00bb SalzburgerLand.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/gastein-nina-zwischen-nostalgie-und-moderne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/gastein-nina-zwischen-nostalgie-und-moderne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/nina-radman-im-gasteinertal_titel.jpg\",\"datePublished\":\"2017-06-27T12:51:22+00:00\",\"dateModified\":\"2025-10-06T12:22:29+00:00\",\"description\":\"Zu Besuch im Gasteinertal: Die Bloggerin Nina Radman aka Berries & Passion hat das SalzburgerLand erkundet und teilt ihre Geheimtipps mit uns.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/gastein-nina-zwischen-nostalgie-und-moderne\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/gastein-nina-zwischen-nostalgie-und-moderne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/gastein-nina-zwischen-nostalgie-und-moderne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/nina-radman-im-gasteinertal_titel.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/nina-radman-im-gasteinertal_titel.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"\u00a9 SalzburgerLand Tourismus, Jonathan Forsthuber \u2013 Nina auf der H\u00e4ngebr\u00fccke\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/gastein-nina-zwischen-nostalgie-und-moderne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Berries &amp; Passion\",\"item\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/berries-passion\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GASTEIN: Nina zwischen Nostalgie und Moderne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/\",\"name\":\"SalzburgerLand.com\",\"description\":\"Ihr Urlaub in Salzburg, \u00d6sterreich\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/#organization\",\"name\":\"SalzburgerLand Tourismus GmbH\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/salzburgerland-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/salzburgerland-logo.jpg\",\"width\":1920,\"height\":827,\"caption\":\"SalzburgerLand Tourismus GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/salzburgerland\\\/\",\"https:\\\/\\\/x.com\\\/Salzburgerland\",\"https:\\\/\\\/www.instagram.com\\\/salzburgerland\\\/\",\"http:\\\/\\\/dbpedia.org\\\/resource\\\/Salzburg_(state)\",\"http:\\\/\\\/wikidata.dbpedia.org\\\/resource\\\/Q43325\",\"https:\\\/\\\/open.salzburgerland.com\\\/de\\\/entity\\\/salzburgerland\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/salzburgerland\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/#\\\/schema\\\/person\\\/5e2487151f535fd7a40628d570ca94d3\",\"name\":\"Miriam Kreiseder\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c432f8977c6ef3b4ef5a56e4aae9e3515c8875144022177ab7fa4e8696a5b7cb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c432f8977c6ef3b4ef5a56e4aae9e3515c8875144022177ab7fa4e8696a5b7cb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c432f8977c6ef3b4ef5a56e4aae9e3515c8875144022177ab7fa4e8696a5b7cb?s=96&d=mm&r=g\",\"caption\":\"Miriam Kreiseder\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"GASTEIN: Nina zwischen Nostalgie und Moderne \u00bb SalzburgerLand.com","description":"Zu Besuch im Gasteinertal: Die Bloggerin Nina Radman aka Berries & Passion hat das SalzburgerLand erkundet und teilt ihre Geheimtipps mit uns.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts\/155231","og_locale":"de_DE","og_type":"article","og_title":"GASTEIN: Nina zwischen Nostalgie und Moderne","og_description":"Zu Besuch im Gasteinertal: Die Bloggerin Nina Radman aka Berries & Passion hat das SalzburgerLand erkundet und teilt ihre Geheimtipps mit uns.","og_url":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts\/155231","og_site_name":"SalzburgerLand.com","article_publisher":"https:\/\/www.facebook.com\/salzburgerland\/","article_published_time":"2017-06-27T12:51:22+00:00","article_modified_time":"2025-10-06T12:22:29+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/nina-radman-im-gasteinertal_titel-1200x675.jpg","type":"image\/jpeg"}],"author":"Miriam Kreiseder","twitter_card":"summary_large_image","twitter_creator":"@Salzburgerland","twitter_site":"@Salzburgerland","twitter_misc":{"Verfasst von":"Miriam Kreiseder","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.salzburgerland.com\/de\/gastein-nina-zwischen-nostalgie-und-moderne\/","url":"https:\/\/www.salzburgerland.com\/de\/gastein-nina-zwischen-nostalgie-und-moderne\/","name":"GASTEIN: Nina zwischen Nostalgie und Moderne \u00bb SalzburgerLand.com","isPartOf":{"@id":"https:\/\/www.salzburgerland.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salzburgerland.com\/de\/gastein-nina-zwischen-nostalgie-und-moderne\/#primaryimage"},"image":{"@id":"https:\/\/www.salzburgerland.com\/de\/gastein-nina-zwischen-nostalgie-und-moderne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/nina-radman-im-gasteinertal_titel.jpg","datePublished":"2017-06-27T12:51:22+00:00","dateModified":"2025-10-06T12:22:29+00:00","description":"Zu Besuch im Gasteinertal: Die Bloggerin Nina Radman aka Berries & Passion hat das SalzburgerLand erkundet und teilt ihre Geheimtipps mit uns.","breadcrumb":{"@id":"https:\/\/www.salzburgerland.com\/de\/gastein-nina-zwischen-nostalgie-und-moderne\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salzburgerland.com\/de\/gastein-nina-zwischen-nostalgie-und-moderne\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salzburgerland.com\/de\/gastein-nina-zwischen-nostalgie-und-moderne\/#primaryimage","url":"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/nina-radman-im-gasteinertal_titel.jpg","contentUrl":"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/06\/nina-radman-im-gasteinertal_titel.jpg","width":1920,"height":1080,"caption":"\u00a9 SalzburgerLand Tourismus, Jonathan Forsthuber \u2013 Nina auf der H\u00e4ngebr\u00fccke"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salzburgerland.com\/de\/gastein-nina-zwischen-nostalgie-und-moderne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Berries &amp; Passion","item":"https:\/\/www.salzburgerland.com\/de\/berries-passion\/"},{"@type":"ListItem","position":2,"name":"GASTEIN: Nina zwischen Nostalgie und Moderne"}]},{"@type":"WebSite","@id":"https:\/\/www.salzburgerland.com\/de\/#website","url":"https:\/\/www.salzburgerland.com\/de\/","name":"SalzburgerLand.com","description":"Ihr Urlaub in Salzburg, \u00d6sterreich","publisher":{"@id":"https:\/\/www.salzburgerland.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salzburgerland.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.salzburgerland.com\/de\/#organization","name":"SalzburgerLand Tourismus GmbH","url":"https:\/\/www.salzburgerland.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salzburgerland.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/01\/salzburgerland-logo.jpg","contentUrl":"https:\/\/www.salzburgerland.com\/de\/wp-content\/uploads\/2017\/01\/salzburgerland-logo.jpg","width":1920,"height":827,"caption":"SalzburgerLand Tourismus GmbH"},"image":{"@id":"https:\/\/www.salzburgerland.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/salzburgerland\/","https:\/\/x.com\/Salzburgerland","https:\/\/www.instagram.com\/salzburgerland\/","http:\/\/dbpedia.org\/resource\/Salzburg_(state)","http:\/\/wikidata.dbpedia.org\/resource\/Q43325","https:\/\/open.salzburgerland.com\/de\/entity\/salzburgerland","https:\/\/www.youtube.com\/user\/salzburgerland"]},{"@type":"Person","@id":"https:\/\/www.salzburgerland.com\/de\/#\/schema\/person\/5e2487151f535fd7a40628d570ca94d3","name":"Miriam Kreiseder","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c432f8977c6ef3b4ef5a56e4aae9e3515c8875144022177ab7fa4e8696a5b7cb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c432f8977c6ef3b4ef5a56e4aae9e3515c8875144022177ab7fa4e8696a5b7cb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c432f8977c6ef3b4ef5a56e4aae9e3515c8875144022177ab7fa4e8696a5b7cb?s=96&d=mm&r=g","caption":"Miriam Kreiseder"}}]}},"_wl_alt_label":[],"wl:entity_url":"https:\/\/open.salzburgerland.com\/de\/post\/nina_entdeckt_das_gasteinertal","_links":{"self":[{"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts\/155231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/comments?post=155231"}],"version-history":[{"count":2,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts\/155231\/revisions"}],"predecessor-version":[{"id":678856,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/posts\/155231\/revisions\/678856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/media\/155232"}],"wp:attachment":[{"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/media?parent=155231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/categories?post=155231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/tags?post=155231"},{"taxonomy":"wl_entity_type","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/wp-json\/wp\/v2\/wl_entity_type?post=155231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}