{"id":20953,"date":"2012-07-17T10:07:09","date_gmt":"2012-07-17T08:07:09","guid":{"rendered":"http:\/\/magazin.salzburgerland.com\/?p=20953"},"modified":"2023-06-22T10:07:45","modified_gmt":"2023-06-22T08:07:45","slug":"365-tage-auf-der-alm","status":"publish","type":"post","link":"https:\/\/www.salzburgerland.com\/de\/magazin\/365-tage-auf-der-alm\/","title":{"rendered":"365 Tage auf der Alm"},"content":{"rendered":"<p>Kein Strom, kein Auto, kein Handy oder PC, kein Einkaufen \u2013 ein Jahr autark als Selbstversorgerin auf einer Alm auf \u00fcber 1 200 m Seeh\u00f6he leben. Roswitha Huber aus <a href=\"http:\/\/www.raurisertal.at\">Rauris <\/a>startete im Mai 2012 ihr ganz pers\u00f6nliches Experiment auf der <a href=\"http:\/\/www.schule-am-berg.at\">Kalchkendlalm <\/a>und wird bis Mai 2013 nur von dem leben, was sie selbst anpflanzt und erzeugt.<\/p>\n<p>Die 57-j\u00e4hrige geb\u00fcrtige Ober\u00f6sterreicherin war als Volksschullehrerin 1976 nach Rauris-W\u00f6rth gekommen, heiratete einen Bauern und ist Mutter von 5 Kindern. Sie steht mit beiden Beinen fest im Leben und ihre Augen unter dem rotblonden Haarschopf strahlen St\u00e4rke und einen eisernen Willen aus. Sie ist immer schon ihren eigenen Weg gegangen, und so hing sie ihren Beruf als Lehrerin 1996 an den Nagel um auf der Kalchkendlalm ihre eigene Schule zu gr\u00fcnden: <a href=\"http:\/\/www.schule-am-berg.at\">Die Schule am Berg<\/a>. Mit Brotbackkursen (mehr dar\u00fcber in meinem <a title=\"Das t\u00e4gliche Brot der Eigenbr\u00f6tlerin: einfach gut!\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/essen-trinken\/das-tagliche-brot-der-eigenbrotlerin-einfach-gut\/\" target=\"_blank\" rel=\"noopener noreferrer\">Artikel: Das Brot der Eigenbr\u00f6tlerin<\/a>), Seminaren, Lesungen und Symposien hat sich Roswitha bereits \u00fcber die Landesgrenzen hinaus einen Namen gemacht und ihr \u201eWissen rund ums Brot\u201c hat die Autorin zweier B\u00fccher sogar bis nach Madagaskar gebracht, wo sie einen alten Brotbackofen wieder instand setzte.<\/p>\n<p><a href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/lifestyle\/365-tage-auf-der-alm\/attachment\/aussicht-2\/\" rel=\"attachment wp-att-20956\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-magazine-halb wp-image-20956\" title=\"aussicht\" alt=\"\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2012\/07\/aussicht-300x225.jpg\" width=\"300\" height=\"225\"><\/a>&nbsp;<a href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/lifestyle\/365-tage-auf-der-alm\/attachment\/huehner\/\" rel=\"attachment wp-att-20959\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-magazine-halb wp-image-20959\" title=\"huehner\" alt=\"\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2012\/07\/huehner-300x225.jpg\" width=\"300\" height=\"225\"><\/a><\/p>\n<p><strong>Tue es ganz!<\/strong><\/p>\n<p>F\u00fcr Roswitha Huber z\u00e4hlen keine halben Sachen und so erz\u00e4hlt sie bei einem frischen Butterbrot auf dem sonnigen Hausbankerl vor der Alm: \u201eIch sagte mir damals \u2013 tue es ganz! Und so konzentriere ich mich seit 8 Jahren v\u00f6llig auf die Arbeit hier heroben auf der Kalchkendlalm. Auch wenn Brot das zentrale Thema ist, geht es vorrangig um die Sensibilisierung f\u00fcr das Echte und eine Basiswissensvermittlung, wo unsere Lebensmittel herkommen. Brot ist daf\u00fcr einfach ein sch\u00f6nes Produkt: keiner hat Aversionen dagegen, man isst sich nicht ab, du kannst damit \u00fcberleben, es ist haltbar und vor allem f\u00fcr alle Altersgruppen in der Herstellung erlebbar.\u201c<\/p>\n<p>Bis vor siebzig Jahren lebte auf der heutigen Kalchkendlalm eine vierzehnk\u00f6pfige Familie in weitgehender Selbstversorgung. Die B\u00e4uerin starb bei der Geburt ihres dreizehnten Kindes und so ging der Hof 1957 in den Besitz der Familie Huber \u00fcber. Dieses autarke Leben inspirierte Roswitha Huber zu ihrem 365-Tage-Selbstversuch. Mit 1. Mai 2012 startete sie ihr Projekt auf der Kalchkendlalm und lebt nur noch von dem, was sie selbst anbaut und erzeugt. Ein Jahr lang nichts einkaufen und kein Geld f\u00fcr sich ausgeben sind die Vorgaben, die sie sich selbst auferlegt hat. \u201eEs geht dabei um Selbstversorgung, nicht um ein Eremiten-Dasein. Es kommen nach wie vor viele Besucher und auch meine Brotbackkurse f\u00fchre ich fort. Ich habe ja meine Kinder zu versorgen und so kann ich es mir nicht leisten, nichts zu verdienen. Sonst h\u00e4tte ich dieses Projekt auf der Hochalm auf 2 000 m durchgef\u00fchrt, wo ich wirklich allein gewesen w\u00e4re,\u201c erkl\u00e4rt sie mit Blick auf die Wanderer, die gerade das h\u00f6lzerne Tor zur Alm \u00f6ffnen und f\u00fcgt mit einem Augenzwinkern hinzu: \u201eMein Auftrag ist es, Wissen zu vermitteln \u2013 kein Bier zu verkaufen. Ich bin Anlaufpunkt f\u00fcr wissensdurstige Wanderer, keine Jausenstation.\u201c<\/p>\n<p><a href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/lifestyle\/365-tage-auf-der-alm\/attachment\/ruhe-und-einsamkeit\/\" rel=\"attachment wp-att-20960\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-magazine-halb wp-image-20960\" title=\"ruhe und einsamkeit\" alt=\"\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2012\/07\/ruhe-und-einsamkeit-300x225.jpg\" width=\"300\" height=\"225\"><\/a>&nbsp;<a href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/lifestyle\/365-tage-auf-der-alm\/attachment\/bauerngarten\/\" rel=\"attachment wp-att-20957\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-magazine-halb wp-image-20957\" title=\"bauerngarten\" alt=\"\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2012\/07\/bauerngarten-300x225.jpg\" width=\"300\" height=\"225\"><\/a><\/p>\n<p><strong>&#8222;Das h\u00e4ltst du keine 2 Wochen aus!&#8220;<\/strong><\/p>\n<p>Das Getreide f\u00fcr das Brot kommt von ihrem Cousin, ein paar H\u00fchner, Ziegen und K\u00fche sorgen f\u00fcr Eier und Milch und der gro\u00dfe Bauerngarten hinter der Alm f\u00fcr frisches Gem\u00fcse. Auch der Verzicht auf Mobilit\u00e4t und Kommunikation geh\u00f6rt zu dem Versuch: \u201eKein Auto zu haben, das war schon eine Umstellung. Man muss vorausschauender planen, denn zu Fu\u00df sind die Wege doch recht weit von hier oben. Das Abschalten des Handys allerdings ist mir ganz leicht gefallen. Das nervige L\u00e4uten des Telefons geht mir gar nicht ab und Termine werden jetzt verbindlicher, da man mich nicht einfach anrufen und etwas Ausgemachtes verschieben kann. Ich habe viele Verbindungen in die Welt, doch nun findet Kommunikation nur noch Aug in Aug statt \u2013 wer was von mir will, kommt auf die Alm.\u201c<\/p>\n<p>Eine richtige Vorbereitung f\u00fcr die Auszeit gab es nicht und so startete Roswitha mit vielen ungekl\u00e4rten Fragen in das Projekt. \u201eIch lerne hier heroben so viele neue Dinge. Es kommen viele Sachen auf mich zu, mit denen ich nicht gerechnet habe, doch da muss ich durch! Einer meiner S\u00f6hne zeigte mir das Melken der Gei\u00dfen und kontrolliert meinen Umgang mit den Tieren. Meine Kinder unterst\u00fctzen mein Vorhaben und interessieren sich daf\u00fcr, obwohl meine Tochter anfangs meinte: \u201aDas h\u00e4ltst du keine 14 Tage aus!\u2019\u201c<\/p>\n<p><strong>&#8222;Ich bin angekommen!&#8220;<\/strong><\/p>\n<p>Roswitha wird gerne auch als \u201edie Eigenbr\u00f6tlerin\u201c betitelt, was aber mehr auf ihre Liebe zum Brot anspielt. Denn trotz ihres eigenwilligen Vorhabens ist sie bei weitem kein fanatischer \u00d6ko-Freak, Zivilisations-Verweigernder Aussteiger oder menschenscheuer Eremit, und so liegt auch in all der St\u00e4rke und Ruhe, die Roswitha mit jedem Wort und jeder Geste ausstrahlt ein leichter Hauch von Unsicherheit, wenn sie an den Winter denkt: \u201eMit dem Alleinsein und der Einsamkeit k\u00f6nnte ich schon ein Problem bekommen. Vor allem im Winter, wenn die Tage kurz sind und ich auch einmal durch den Schnee von der Au\u00dfenwelt abgeschnitten bin. Doch daran denke ich jetzt einfach noch nicht!\u201c<\/p>\n<p>Nachrichten aus der Welt kommen zu Roswitha nur noch gefiltert \u2013 nur was ihren Besuchern erz\u00e4hlenswert erscheint, oder was sie durch Briefe erf\u00e4hrt h\u00e4lt sie auf dem Laufenden. Doch den Nachrichten-\u00dcberfluss scheint sie ohnehin nicht zu vermissen, und so meint sie mit einem ruhigen Blick \u00fcber das gr\u00fcne Almgebiet: \u201eIch f\u00fchle mich hier heroben wohler, als unten. Ich bin angekommen. Es gibt gar nichts was mir abgeht.<\/p>\n<p>Bald werde ich Roswitha wieder auf der Kalchkendlalm besuchen, um zu berichten, wie es ihr nach den ersten Monaten auf der Alm ergeht.<\/p>\n<p><em>Wer Roswitha Huber schreiben m\u00f6chte, der mu\u00df zu Papier und Bleistift greifen, denn auch \u00fcber Mail ist sie nat\u00fcrlich nicht erreichbar:<\/em><\/p>\n<p><em>Schule am Berg &#8211; Kalchkendlalm &#8211; Fr\u00f6stlbergweg 44 &#8211; A-5661 Rauris-W\u00f6rth<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kein Strom, kein Auto, kein Handy oder PC, kein Einkaufen \u2013 ein Jahr autark als Selbstversorgerin auf einer Alm auf \u00fcber 1 200 m Seeh\u00f6he leben. Roswitha Huber aus Rauris startete im Mai 2012 ihr ganz pers\u00f6nliches Experiment auf der Kalchkendlalm und wird bis Mai 2013 nur von dem leben, was sie selbst anpflanzt und [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":20958,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wl_entities_gutenberg":"","_wl_entity_redirect_enabled":"","footnotes":""},"categories":[7551],"tags":[],"wl_entity_type":[306],"monatsauswahl":[],"class_list":["post-20953","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archiv","wl_entity_type-article"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>365 Tage auf der Alm - SalzburgerLand Magazin<\/title>\n<meta name=\"description\" content=\"Kein Strom, kein Auto, kein Handy oder PC, kein Einkaufen \u2013 ein Jahr autark als Selbstversorgerin auf einer Alm auf \u00fcber 1 200 m Seeh\u00f6he leben. Roswitha Huber aus Rauris startete im Mai 2012 ihr ganz pers\u00f6nliches Experiment auf der Kalchkendlalm und wird bis Mai 2013 nur von dem leben, was sie selbst anpflanzt und [&hellip;]\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"365 Tage auf der Alm\" \/>\n<meta property=\"og:description\" content=\"Kein Strom, kein Auto, kein Handy oder PC, kein Einkaufen \u2013 ein Jahr autark als Selbstversorgerin auf einer Alm auf \u00fcber 1 200 m Seeh\u00f6he leben. Roswitha Huber aus Rauris startete im Mai 2012 ihr ganz pers\u00f6nliches Experiment auf der Kalchkendlalm und wird bis Mai 2013 nur von dem leben, was sie selbst anpflanzt und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salzburgerland.com\/de\/magazin\/365-tage-auf-der-alm\/\" \/>\n<meta property=\"og:site_name\" content=\"SalzburgerLand Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/salzburgerland\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-07-17T08:07:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-22T08:07:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2012\/07\/header-portrait-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3008\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edith Danzer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Salzburgerland\" \/>\n<meta name=\"twitter:site\" content=\"@Salzburgerland\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edith Danzer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/365-tage-auf-der-alm\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/365-tage-auf-der-alm\\\/\"},\"author\":{\"name\":\"Edith Danzer\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#\\\/schema\\\/person\\\/79452c699c410aa31a119426313748de\"},\"headline\":\"365 Tage auf der Alm\",\"datePublished\":\"2012-07-17T08:07:09+00:00\",\"dateModified\":\"2023-06-22T08:07:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/365-tage-auf-der-alm\\\/\"},\"wordCount\":975,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/365-tage-auf-der-alm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2012\\\/07\\\/header-portrait-scaled.jpg\",\"articleSection\":[\"Archiv\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/365-tage-auf-der-alm\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/365-tage-auf-der-alm\\\/\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/365-tage-auf-der-alm\\\/\",\"name\":\"365 Tage auf der Alm - SalzburgerLand Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/365-tage-auf-der-alm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/365-tage-auf-der-alm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2012\\\/07\\\/header-portrait-scaled.jpg\",\"datePublished\":\"2012-07-17T08:07:09+00:00\",\"dateModified\":\"2023-06-22T08:07:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/365-tage-auf-der-alm\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/365-tage-auf-der-alm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/365-tage-auf-der-alm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2012\\\/07\\\/header-portrait-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2012\\\/07\\\/header-portrait-scaled.jpg\",\"width\":3008,\"height\":2000,\"caption\":\"Eine l\u00e4chelnde Frau lehnt an einer rustikalen H\u00fcttent\u00fcr und h\u00e4lt ein h\u00f6lzernes KALCHGRUBALM-Schild in die H\u00f6he, rote Blumen im Fenster.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/365-tage-auf-der-alm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archiv\",\"item\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/thema\\\/archiv\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"365 Tage auf der Alm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/\",\"name\":\"SalzburgerLand Magazin\",\"description\":\"Geschichten und Interessantes aus dem SalzburgerLand\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#organization\",\"name\":\"SalzburgerLand Tourismus\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/salzburgerland-logo1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/salzburgerland-logo1.jpg\",\"width\":2011,\"height\":866,\"caption\":\"SalzburgerLand Tourismus\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/salzburgerland\\\/\",\"https:\\\/\\\/x.com\\\/Salzburgerland\",\"https:\\\/\\\/www.instagram.com\\\/salzburgerland\\\/\",\"https:\\\/\\\/at.linkedin.com\\\/company\\\/salzburgerland-tourismus-gmbh\",\"https:\\\/\\\/www.pinterest.at\\\/salzburgerland\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/salzburgerland\",\"https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/SalzburgerLand_Tourismus_GmbH\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#\\\/schema\\\/person\\\/79452c699c410aa31a119426313748de\",\"name\":\"Edith Danzer\",\"description\":\"Seit Jahren arbeite ich als freie Redakteurin und Fotografin im SalzburgerLand. Schreiben ist f\u00fcr mich nicht blo\u00df das Erstellen eines Textes. Es ist ein Komponieren einer wundervollen Melodie, ein Malen mit Buchstaben und Worten. Ich liebe die Begegnungen mit Menschen, die mir ihre Geschichte anvertrauen. Wenn man mich sucht, bin ich entweder am Schreibtisch (der auch mal am sonnigen H\u00fcttenbankerl stehen kann) oder mit meinem Husky-M\u00e4dl Ylvi am Berg, am See oder im Wald. Ich \u2026 \u2026 in ein paar Worten. \u2022 Lieber drau\u00dfen, als drinnen. \u2022 Lieber Norden, als S\u00fcden. \u2022 Lieber Buchstaben, als Zahlen. \u2022 Lieber Schnee, als Strand. \u2022 Lieber Berg, als Tal. \u2022 Lieber Nordlichter, als S\u00fcdseezauber. \u2022 Lieber H\u00fctte, als F\u00fcnfsternschuppen. \u2022 Lieber Hund, als Katze. \u2022 Lieber grader Michl, als falscher Fufzga. \u2022 Lieber mittendurch, als drumherum \u2022 Lieber Almleben, als Couchpotato\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/author\\\/edith-danzer\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"365 Tage auf der Alm - SalzburgerLand Magazin","description":"Kein Strom, kein Auto, kein Handy oder PC, kein Einkaufen \u2013 ein Jahr autark als Selbstversorgerin auf einer Alm auf \u00fcber 1 200 m Seeh\u00f6he leben. Roswitha Huber aus Rauris startete im Mai 2012 ihr ganz pers\u00f6nliches Experiment auf der Kalchkendlalm und wird bis Mai 2013 nur von dem leben, was sie selbst anpflanzt und [&hellip;]","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"de_DE","og_type":"article","og_title":"365 Tage auf der Alm","og_description":"Kein Strom, kein Auto, kein Handy oder PC, kein Einkaufen \u2013 ein Jahr autark als Selbstversorgerin auf einer Alm auf \u00fcber 1 200 m Seeh\u00f6he leben. Roswitha Huber aus Rauris startete im Mai 2012 ihr ganz pers\u00f6nliches Experiment auf der Kalchkendlalm und wird bis Mai 2013 nur von dem leben, was sie selbst anpflanzt und [&hellip;]","og_url":"https:\/\/www.salzburgerland.com\/de\/magazin\/365-tage-auf-der-alm\/","og_site_name":"SalzburgerLand Magazin","article_publisher":"https:\/\/www.facebook.com\/salzburgerland\/","article_published_time":"2012-07-17T08:07:09+00:00","article_modified_time":"2023-06-22T08:07:45+00:00","og_image":[{"width":3008,"height":2000,"url":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2012\/07\/header-portrait-scaled.jpg","type":"image\/jpeg"}],"author":"Edith Danzer","twitter_card":"summary_large_image","twitter_creator":"@Salzburgerland","twitter_site":"@Salzburgerland","twitter_misc":{"Verfasst von":"Edith Danzer","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/365-tage-auf-der-alm\/#article","isPartOf":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/365-tage-auf-der-alm\/"},"author":{"name":"Edith Danzer","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#\/schema\/person\/79452c699c410aa31a119426313748de"},"headline":"365 Tage auf der Alm","datePublished":"2012-07-17T08:07:09+00:00","dateModified":"2023-06-22T08:07:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/365-tage-auf-der-alm\/"},"wordCount":975,"commentCount":0,"publisher":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#organization"},"image":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/365-tage-auf-der-alm\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2012\/07\/header-portrait-scaled.jpg","articleSection":["Archiv"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salzburgerland.com\/de\/magazin\/365-tage-auf-der-alm\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/365-tage-auf-der-alm\/","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/365-tage-auf-der-alm\/","name":"365 Tage auf der Alm - SalzburgerLand Magazin","isPartOf":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/365-tage-auf-der-alm\/#primaryimage"},"image":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/365-tage-auf-der-alm\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2012\/07\/header-portrait-scaled.jpg","datePublished":"2012-07-17T08:07:09+00:00","dateModified":"2023-06-22T08:07:45+00:00","breadcrumb":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/365-tage-auf-der-alm\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salzburgerland.com\/de\/magazin\/365-tage-auf-der-alm\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/365-tage-auf-der-alm\/#primaryimage","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2012\/07\/header-portrait-scaled.jpg","contentUrl":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2012\/07\/header-portrait-scaled.jpg","width":3008,"height":2000,"caption":"Eine l\u00e4chelnde Frau lehnt an einer rustikalen H\u00fcttent\u00fcr und h\u00e4lt ein h\u00f6lzernes KALCHGRUBALM-Schild in die H\u00f6he, rote Blumen im Fenster."},{"@type":"BreadcrumbList","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/365-tage-auf-der-alm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.salzburgerland.com\/de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Archiv","item":"https:\/\/www.salzburgerland.com\/de\/magazin\/thema\/archiv\/"},{"@type":"ListItem","position":3,"name":"365 Tage auf der Alm"}]},{"@type":"WebSite","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#website","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/","name":"SalzburgerLand Magazin","description":"Geschichten und Interessantes aus dem SalzburgerLand","publisher":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salzburgerland.com\/de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#organization","name":"SalzburgerLand Tourismus","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#\/schema\/logo\/image\/","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2019\/06\/salzburgerland-logo1.jpg","contentUrl":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2019\/06\/salzburgerland-logo1.jpg","width":2011,"height":866,"caption":"SalzburgerLand Tourismus"},"image":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/salzburgerland\/","https:\/\/x.com\/Salzburgerland","https:\/\/www.instagram.com\/salzburgerland\/","https:\/\/at.linkedin.com\/company\/salzburgerland-tourismus-gmbh","https:\/\/www.pinterest.at\/salzburgerland\/","https:\/\/www.youtube.com\/user\/salzburgerland","https:\/\/de.wikipedia.org\/wiki\/SalzburgerLand_Tourismus_GmbH"]},{"@type":"Person","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#\/schema\/person\/79452c699c410aa31a119426313748de","name":"Edith Danzer","description":"Seit Jahren arbeite ich als freie Redakteurin und Fotografin im SalzburgerLand. Schreiben ist f\u00fcr mich nicht blo\u00df das Erstellen eines Textes. Es ist ein Komponieren einer wundervollen Melodie, ein Malen mit Buchstaben und Worten. Ich liebe die Begegnungen mit Menschen, die mir ihre Geschichte anvertrauen. Wenn man mich sucht, bin ich entweder am Schreibtisch (der auch mal am sonnigen H\u00fcttenbankerl stehen kann) oder mit meinem Husky-M\u00e4dl Ylvi am Berg, am See oder im Wald. Ich \u2026 \u2026 in ein paar Worten. \u2022 Lieber drau\u00dfen, als drinnen. \u2022 Lieber Norden, als S\u00fcden. \u2022 Lieber Buchstaben, als Zahlen. \u2022 Lieber Schnee, als Strand. \u2022 Lieber Berg, als Tal. \u2022 Lieber Nordlichter, als S\u00fcdseezauber. \u2022 Lieber H\u00fctte, als F\u00fcnfsternschuppen. \u2022 Lieber Hund, als Katze. \u2022 Lieber grader Michl, als falscher Fufzga. \u2022 Lieber mittendurch, als drumherum \u2022 Lieber Almleben, als Couchpotato","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/author\/edith-danzer\/"}]}},"_wl_alt_label":[],"wl:entity_url":"http:\/\/open.salzburgerland.com\/magazin\/post\/365_tage_auf_der_alm","_links":{"self":[{"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/posts\/20953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/comments?post=20953"}],"version-history":[{"count":1,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/posts\/20953\/revisions"}],"predecessor-version":[{"id":169142,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/posts\/20953\/revisions\/169142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/media\/20958"}],"wp:attachment":[{"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/media?parent=20953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/categories?post=20953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/tags?post=20953"},{"taxonomy":"wl_entity_type","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/wl_entity_type?post=20953"},{"taxonomy":"monatsauswahl","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/monatsauswahl?post=20953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}