{"id":174616,"date":"2024-01-04T07:00:00","date_gmt":"2024-01-04T06:00:00","guid":{"rendered":"https:\/\/www.salzburgerland.com\/de\/magazin\/?p=174616"},"modified":"2023-12-06T07:05:44","modified_gmt":"2023-12-06T06:05:44","slug":"im-joja-gustieren-geniessen-und-rundum-wohlfuehlen","status":"publish","type":"post","link":"https:\/\/www.salzburgerland.com\/de\/magazin\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\/","title":{"rendered":"Im JOJA Gustieren, Genie\u00dfen und rundum wohlf\u00fchlen"},"content":{"rendered":"\n<div class=\"wp-block-slt-top topBlocks\">\n<h2 class=\"wp-block-slt-subtitle\">Salzburgs erstes Sharing-Restaurant <\/h2>\n\n\n\n<p class=\"wp-block-slt-intro\">Josef Hausner und Jakob Karntner zeigen in ihrem Restaurant am Franz-Josef-Kai, wie entspannt und gleichzeitig am Puls der Zeit Kulinarik-Konzepte genossen werden k\u00f6nnen. Ob man die feinen K\u00f6stlichkeiten der \u201eTaste 2 Share\u201c Karte nun mit wem anderen teilt oder sich die Gerichte alleine g\u00f6nnt, soviel ist klar: Bei einem einzigen Gang bleibt es sicher nicht!<\/p>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ein-perfektes-gastro-match-josef-amp-jakob\">Ein perfektes Gastro-Match: JOsef &amp; JAkob<\/h2>\n\n\n\n<p>Noch keine 30 Lenze z\u00e4hlen die JOJA-Gastgeber Josef und Jakob \u2013\u00a0und trotzdem k\u00f6nnen beide schon auf eine beeindruckende Gastronomie-Laufbahn zur\u00fcckblicken. Die startete bei beiden in der Tourismusschule Kle\u00dfheim in Salzburg. Dort trafen der geb\u00fcrtige Bayer Josef und der aus Nieder\u00f6sterreich stammende Jakob erstmals aufeinander, bevor es Josef nach der Matura zun\u00e4chst nach Amerika zog und es f\u00fcr ihn danach beim Genussdorf Gmachl in Bergheim weiterging. Jakob eroberte K\u00fcchen in Amsterdam und Dublin, bevor er f\u00fcr zwei Jahre bei Sternekoch Andreas Senn in SENNS.Restaurant in Salzburg anheuerte.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"4823\" height=\"6431\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/JoJa-Sujet-Kein-Text-edited.png\" alt=\"Josef Hausner und Jakob Karntner \u2013 Gastgeber im JOJA\" class=\"wp-image-174632\" style=\"object-fit:cover\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/JoJa-Sujet-Kein-Text-edited.png 4823w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/JoJa-Sujet-Kein-Text-edited-225x300.png 225w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/JoJa-Sujet-Kein-Text-edited-1152x1536.png 1152w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/JoJa-Sujet-Kein-Text-edited-1536x2048.png 1536w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/JoJa-Sujet-Kein-Text-edited-412x550.png 412w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/JoJa-Sujet-Kein-Text-edited-768x1024.png 768w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/JoJa-Sujet-Kein-Text-edited-300x400.png 300w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/JoJa-Sujet-Kein-Text-edited-1320x1760.png 1320w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/JoJa-Sujet-Kein-Text-edited-640x853.png 640w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/JoJa-Sujet-Kein-Text-edited-150x200.png 150w\" sizes=\"auto, (max-width: 4823px) 100vw, 4823px\" \/><\/figure>\n<\/div>\n\n\n<p>Wiedergetroffen hat man sich auf der steirischen Gretlh\u00fctte, die Jakob zwei Sommer lang gef\u00fchrt hat und in der Josef den zweiten Sommer mit angepackt hat. Ein schicksalstr\u00e4chtiger Sommer 2022, wie sich sp\u00e4ter herausstellen sollte \u2013 denn bei dem einen oder anderen Kaltgetr\u00e4nk war den beiden Schulfreunden klar: Sie haben gastronomisch noch Gro\u00dfes vor. Die Selbst\u00e4ndigkeit schwirrte Jakob schon lange im Kopf herum, sollte die passende Location gefunden werden \u2013 der Rest ist Geschichte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-joja-ein-ort-zum-geniessen-amp-wohlfuhlen\">JOJA: Ein Ort zum Genie\u00dfen &amp; Wohlf\u00fchlen<\/h2>\n\n\n\n<p>\u201eGesucht und gefunden\u201c: So rekapitulieren Jakob und Josef den Weg zu ihrem heutigen JOJA-Standort am Franz-Josef-Kai in der Salzburger Altstadt heute. Ganz nach dem erfrischenden Motto \u201eschauen wir mal, was passiert\u201c, haben sie sich die Location angesehen \u2013 und binnen drei Tagen \u00fcbernommen. \u201eMan k\u00f6nnte sagen, wir sind richtig reingestolpert\u201c, schmunzeln die beiden JOJA-Gastgeber. Dass das die richtige Entscheidung war, zeigt sich beim Betreten des Lokals. Denn nicht nur Josef und Jakob sind auf einer Gastro-Wellenl\u00e4nge, auch die Location, die innen etwa Platz f\u00fcr 40 Personen bietet, passt perfekt zu ihnen \u2013 unkompliziert, sympathisch, gleichzeitig gef\u00fcllt mit vielen kleinen Highlights zum Entdecken und Schmunzeln. Absolut genial ist der im Innenhof liegende Gastgarten, der in den warmen Monaten des Jahres eine richtige Chill-Oase f\u00fcr etwa 60 Personen ist, um sowohl den warmen Temperaturen als auch dem regen Altstadt-Treiben w\u00e4hrend der Festspielzeit ein wenig zu entkommen.<\/p>\n\n\n<div class=\"mag-gallery\"><div class=\"row\"><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07274-Bearbeitet-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07274-Bearbeitet-325x209.jpg 325w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07274-Bearbeitet-249x160.jpg 249w\"><\/source><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07274-Bearbeitet-249x160.jpg 249w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07274-Bearbeitet-325x209.jpg 325w\"><\/source><img decoding=\"async\" alt=\"Farbenfrohes Restaurant mit kunstvollen St&uuml;hlen und einer kr&auml;ftigen roten Wand, die mit Spiegeln und gemalten Gesichtern verziert ist.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07274-Bearbeitet-scaled.jpg\">\t<\/picture><figcaption>Fancyness im JOJA-Style @JOJA<\/figcaption><\/a><\/figure><\/div><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07418-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07418-325x209.jpg 325w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07418-249x160.jpg 249w\"><\/source><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07418-249x160.jpg 249w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07418-325x209.jpg 325w\"><\/source><img decoding=\"async\" alt=\"Essbereich auf der Terrasse mit leeren Tischen und St&uuml;hlen, umgeben von &uuml;ppigem Gr&uuml;n und Pflanzen.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07418-scaled.jpg\">\t<\/picture><figcaption>Der sensationelle JOJA Gastgarten @JOJA<\/figcaption><\/a><\/figure><\/div><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07199-Bearbeitet-Bearbeitet-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07199-Bearbeitet-Bearbeitet-325x209.jpg 325w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07199-Bearbeitet-Bearbeitet-249x160.jpg 249w\"><\/source><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07199-Bearbeitet-Bearbeitet-249x160.jpg 249w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07199-Bearbeitet-Bearbeitet-325x209.jpg 325w\"><\/source><img decoding=\"async\" alt=\"Gem&uuml;tliches Restaurant mit bunten Kissen, Holztischen und sanfter Beleuchtung, mit einem gro&szlig;en Fenster mit Pflanzen.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07199-Bearbeitet-Bearbeitet-scaled.jpg\">\t<\/picture><figcaption>Willkommen im JOJA Sharing-Restaurant @JOJA<\/figcaption><\/a><\/figure><\/div><\/div><figcaption><\/figcaption><\/div>\n\n\n\n<p>Ob f\u00fcr ein gem\u00fctliches Snacken und Drinks-Genie\u00dfen mit Freunden, ein After-Work-Platzerl zum Dinieren und Absacker-Trinken oder ein First (und Second, Third, Fourth &#8230;) Date mit dem Lieblingsmenschen: Das JOJA ist f\u00fcr jedes dieser und vieler weiterer Vorhaben die ideale Location. Ob man nun einfach einen gem\u00fctlichen Drink mit einem kleinen Teller zum Gustieren zu sich nehmen m\u00f6chte oder richtig Hunger mitbringt \u2013 hier im Franz-Josef-Kai 11 is(s)t man richtig. Wobei so viel feststeht: Wer sich hier nicht durch die Karte probiert, hat was verpasst!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-taste-2-share-wenn-man-will\">Taste 2 Share \u2013 wenn man will!<\/h2>\n\n\n\n<p>So, jetzt geht\u2019s ans Eingemachte. Oder besser gesagt: ans Aufgetischte! Im Sharing-Restaurant JOJA ist die grunds\u00e4tzliche Idee, dass man alle Kreationen der Karte wunderbar teilen kann \u2013&nbsp;sofern man das m\u00f6chte, denn die Gerichte sind so wunderbar kreativ konzipiert, abgeschmeckt und angerichtet, dass man sie auch herrlich f\u00fcr sich allein beanspruchen kann. Die Karte, die etwa alle zwei Monate wechselt, setzt sich aus Snacks, Sharing Plates und Nachspeisen zusammen. Unsere Empfehlung: Zun\u00e4chst mal die Kalbsbriesnuggets mit Essiggurkerlmayo bestellen, und w\u00e4hrend man mit ihnen den ersten Gusto stillt, entspannt die restliche Karte durchgehen.<\/p>\n\n\n<div class=\"mag-gallery\"><div class=\"row\"><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC04093-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC04093-418x650.jpg 418w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC04093-209x325.jpg 209w\"><\/source><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC04093-209x325.jpg 209w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC04093-418x650.jpg 418w\"><\/source><img decoding=\"async\" alt=\"Eine Sch&uuml;ssel mit cremiger, geschichteter Pasta, die mit leuchtenden Kr&auml;utern, knusprigen St&uuml;ckchen und gew&uuml;rfelter roter Beilage auf einem Holztisch angerichtet ist.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC04093-scaled.jpg\">\t<\/picture><figcaption>&#8222;Falscher Germkn&ouml;del&#8220; im JOJA &copy;JOJA<\/figcaption><\/a><\/figure><\/div><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07827-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07827-418x650.jpg 418w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07827-209x325.jpg 209w\"><\/source><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07827-209x325.jpg 209w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07827-418x650.jpg 418w\"><\/source><img decoding=\"async\" alt=\"Ein Tisch mit verschiedenen Gerichten, Kerzen, Wein und Menschen, die Essen servieren, bei einer lebhaften Mahlzeit.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07827-scaled.jpg\">\t<\/picture><figcaption>Gerichte zum Teilen &ndash; wenn man m&ouml;chte @JOJA<\/figcaption><\/a><\/figure><\/div><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC03828-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC03828-418x650.jpg 418w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC03828-209x325.jpg 209w\"><\/source><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC03828-209x325.jpg 209w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC03828-418x650.jpg 418w\"><\/source><img decoding=\"async\" alt=\"Goldene Bl&auml;tterteigr&ouml;llchen mit Feigen, Waln&uuml;ssen, cremigem Aufstrich und Kr&auml;utern auf einem wei&szlig;en Teller.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC03828-scaled.jpg\">\t<\/picture><figcaption>&#8222;Feta Saganaki&#8220; JOJA-Style &copy;JOJA<\/figcaption><\/a><\/figure><\/div><\/div><figcaption><\/figcaption><\/div>\n\n\n\n<p>Alle Gerichte im Joja haben Vorspeisengr\u00f6\u00dfe \u2013 das ist optimal, um z.B. alleine den kleinen (oder gro\u00dfen) Hunger mit 1, 2, 3 &#8230; JOJA -Leckereien zu stillen, oder um in ein paar Durchg\u00e4ngen mehrere Gerichte f\u00fcr mehrere Personen zu bestellen. Dann werden sie in die Mitte eingestellt und man kann nehmen, was einem gerade zusagt. Oberstes Credo dabei: kein Stress! Josef, Jakob und ihr Team kommen gerne sp\u00e4ter nochmal vorbei, wenn ihr euch nicht sicher seid, mit wie vielen Sharing Plates ihr es angehen m\u00f6chtet. Denn bei Gerichten wie \u201eCrispy Melanzani\u201c, \u201eFalscher Germkn\u00f6del\u201c, \u201eSai BLING-BLING\u201c, \u201eFeta Saganaki\u201c oder \u201eSweetSweet Potato\u201c kann man schon mal schwach werden, und noch eine zweite Runde bestellen. Falls man sich gar nicht entscheiden kann: Tischweise wird auch eine \u201eJOJA All In\u201c Variante angeboten, bei der die Gastgeber die ganze Karte in mehreren Akten kredenzen. Erg\u00e4nzt wird das Speisenangebot, das sich immer ausgewogen aus Fisch, Fleisch sowie Veggie- und Vegan-Varianten zusammensetzt, mit einer feinen Getr\u00e4nkeauswahl und einer scharfsinnig zusammengestellten \u201eWein(kartei-)karte\u201c.<\/p>\n\n\n\n<p>\u201eUnd wohin geht die Reise des JOJA?\u201c, fragen wir Jakob und Josef abschlie\u00dfend. Sie sind sich einig: \u201eWir wollen noch geiler werden\u201c. Und daran haben wir absolut keinen Zweifel, denken wir uns, w\u00e4hrend wir als \u201eDessert\u201c nochmal einen zweiten Kalbsbriesnuggets-Durchgang genie\u00dfen.<\/p>\n\n\n\n<p><strong>JOJA<\/strong><br>Franz-Josef-Kai 11<br>5020 Salzburg<br>T: +43 676 7554160<br><a href=\"https:\/\/joja.at\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/joja.at<\/a><\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Ein perfektes Gastro-Match: JOsef &amp; JAkob Noch keine 30 Lenze z\u00e4hlen die JOJA-Gastgeber Josef und Jakob \u2013\u00a0und trotzdem k\u00f6nnen beide schon auf eine beeindruckende Gastronomie-Laufbahn zur\u00fcckblicken. Die startete bei beiden in der Tourismusschule Kle\u00dfheim in Salzburg. Dort trafen der geb\u00fcrtige Bayer Josef und der aus Nieder\u00f6sterreich stammende Jakob erstmals aufeinander, bevor es Josef nach der [&hellip;]<\/p>\n","protected":false},"author":586,"featured_media":174618,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wl_entities_gutenberg":"","_wl_entity_redirect_enabled":"","footnotes":""},"categories":[3],"tags":[],"wl_entity_type":[306],"monatsauswahl":[82,83,84,85,86,87,88,89,90,91,92,93],"class_list":["post-174616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-essen-trinken","wl_entity_type-article","monatsauswahl-monat_1","monatsauswahl-monat_2","monatsauswahl-monat_3","monatsauswahl-monat_4","monatsauswahl-monat_5","monatsauswahl-monat_6","monatsauswahl-monat_7","monatsauswahl-monat_8","monatsauswahl-monat_9","monatsauswahl-monat_10","monatsauswahl-monat_11","monatsauswahl-monat_12"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Im JOJA Gustieren, Genie\u00dfen und rundum wohlf\u00fchlen - SalzburgerLand Magazin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Im JOJA Gustieren, Genie\u00dfen und rundum wohlf\u00fchlen\" \/>\n<meta property=\"og:description\" content=\"Ein perfektes Gastro-Match: JOsef &amp; JAkob Noch keine 30 Lenze z\u00e4hlen die JOJA-Gastgeber Josef und Jakob \u2013\u00a0und trotzdem k\u00f6nnen beide schon auf eine beeindruckende Gastronomie-Laufbahn zur\u00fcckblicken. Die startete bei beiden in der Tourismusschule Kle\u00dfheim in Salzburg. Dort trafen der geb\u00fcrtige Bayer Josef und der aus Nieder\u00f6sterreich stammende Jakob erstmals aufeinander, bevor es Josef nach der [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salzburgerland.com\/de\/magazin\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\/\" \/>\n<meta property=\"og:site_name\" content=\"SalzburgerLand Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/salzburgerland\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-04T06:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07711-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martina Baumgartner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Salzburgerland\" \/>\n<meta name=\"twitter:site\" content=\"@Salzburgerland\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martina Baumgartner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\\\/\"},\"author\":{\"name\":\"Martina Baumgartner\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#\\\/schema\\\/person\\\/26faa186b30a5495209f4129e1cff1f6\"},\"headline\":\"Im JOJA Gustieren, Genie\u00dfen und rundum wohlf\u00fchlen\",\"datePublished\":\"2024-01-04T06:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\\\/\"},\"wordCount\":848,\"publisher\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/DSC07711-scaled.jpg\",\"articleSection\":[\"Essen &amp; Trinken\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\\\/\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\\\/\",\"name\":\"Im JOJA Gustieren, Genie\u00dfen und rundum wohlf\u00fchlen - SalzburgerLand Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/DSC07711-scaled.jpg\",\"datePublished\":\"2024-01-04T06:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/DSC07711-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/DSC07711-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"JOJA \u2013 Salzburgs erstes Sharing-Restaurant \u00a9JOJA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Essen &amp; Trinken\",\"item\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/thema\\\/essen-trinken\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Im JOJA Gustieren, Genie\u00dfen und rundum wohlf\u00fchlen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/\",\"name\":\"SalzburgerLand Magazin\",\"description\":\"Geschichten und Interessantes aus dem SalzburgerLand\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#organization\",\"name\":\"SalzburgerLand Tourismus\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/salzburgerland-logo1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/salzburgerland-logo1.jpg\",\"width\":2011,\"height\":866,\"caption\":\"SalzburgerLand Tourismus\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/salzburgerland\\\/\",\"https:\\\/\\\/x.com\\\/Salzburgerland\",\"https:\\\/\\\/www.instagram.com\\\/salzburgerland\\\/\",\"https:\\\/\\\/at.linkedin.com\\\/company\\\/salzburgerland-tourismus-gmbh\",\"https:\\\/\\\/www.pinterest.at\\\/salzburgerland\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/salzburgerland\",\"https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/SalzburgerLand_Tourismus_GmbH\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#\\\/schema\\\/person\\\/26faa186b30a5495209f4129e1cff1f6\",\"name\":\"Martina Baumgartner\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/author\\\/mbaumgartner\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Im JOJA Gustieren, Genie\u00dfen und rundum wohlf\u00fchlen - SalzburgerLand Magazin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salzburgerland.com\/de\/magazin\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\/","og_locale":"de_DE","og_type":"article","og_title":"Im JOJA Gustieren, Genie\u00dfen und rundum wohlf\u00fchlen","og_description":"Ein perfektes Gastro-Match: JOsef &amp; JAkob Noch keine 30 Lenze z\u00e4hlen die JOJA-Gastgeber Josef und Jakob \u2013\u00a0und trotzdem k\u00f6nnen beide schon auf eine beeindruckende Gastronomie-Laufbahn zur\u00fcckblicken. Die startete bei beiden in der Tourismusschule Kle\u00dfheim in Salzburg. Dort trafen der geb\u00fcrtige Bayer Josef und der aus Nieder\u00f6sterreich stammende Jakob erstmals aufeinander, bevor es Josef nach der [&hellip;]","og_url":"https:\/\/www.salzburgerland.com\/de\/magazin\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\/","og_site_name":"SalzburgerLand Magazin","article_publisher":"https:\/\/www.facebook.com\/salzburgerland\/","article_published_time":"2024-01-04T06:00:00+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07711-scaled.jpg","type":"image\/jpeg"}],"author":"Martina Baumgartner","twitter_card":"summary_large_image","twitter_creator":"@Salzburgerland","twitter_site":"@Salzburgerland","twitter_misc":{"Verfasst von":"Martina Baumgartner","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\/#article","isPartOf":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\/"},"author":{"name":"Martina Baumgartner","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#\/schema\/person\/26faa186b30a5495209f4129e1cff1f6"},"headline":"Im JOJA Gustieren, Genie\u00dfen und rundum wohlf\u00fchlen","datePublished":"2024-01-04T06:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\/"},"wordCount":848,"publisher":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#organization"},"image":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07711-scaled.jpg","articleSection":["Essen &amp; Trinken"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\/","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\/","name":"Im JOJA Gustieren, Genie\u00dfen und rundum wohlf\u00fchlen - SalzburgerLand Magazin","isPartOf":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\/#primaryimage"},"image":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07711-scaled.jpg","datePublished":"2024-01-04T06:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salzburgerland.com\/de\/magazin\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\/#primaryimage","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07711-scaled.jpg","contentUrl":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2023\/12\/DSC07711-scaled.jpg","width":2560,"height":1707,"caption":"JOJA \u2013 Salzburgs erstes Sharing-Restaurant \u00a9JOJA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.salzburgerland.com\/de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Essen &amp; Trinken","item":"https:\/\/www.salzburgerland.com\/de\/magazin\/thema\/essen-trinken\/"},{"@type":"ListItem","position":3,"name":"Im JOJA Gustieren, Genie\u00dfen und rundum wohlf\u00fchlen"}]},{"@type":"WebSite","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#website","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/","name":"SalzburgerLand Magazin","description":"Geschichten und Interessantes aus dem SalzburgerLand","publisher":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salzburgerland.com\/de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#organization","name":"SalzburgerLand Tourismus","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#\/schema\/logo\/image\/","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2019\/06\/salzburgerland-logo1.jpg","contentUrl":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2019\/06\/salzburgerland-logo1.jpg","width":2011,"height":866,"caption":"SalzburgerLand Tourismus"},"image":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/salzburgerland\/","https:\/\/x.com\/Salzburgerland","https:\/\/www.instagram.com\/salzburgerland\/","https:\/\/at.linkedin.com\/company\/salzburgerland-tourismus-gmbh","https:\/\/www.pinterest.at\/salzburgerland\/","https:\/\/www.youtube.com\/user\/salzburgerland","https:\/\/de.wikipedia.org\/wiki\/SalzburgerLand_Tourismus_GmbH"]},{"@type":"Person","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#\/schema\/person\/26faa186b30a5495209f4129e1cff1f6","name":"Martina Baumgartner","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/author\/mbaumgartner\/"}]}},"_wl_alt_label":[],"wl:entity_url":"http:\/\/open.salzburgerland.com\/magazin\/post\/im-joja-gustieren-geniessen-und-rundum-wohlfuehlen-174616","_links":{"self":[{"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/posts\/174616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/users\/586"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/comments?post=174616"}],"version-history":[{"count":5,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/posts\/174616\/revisions"}],"predecessor-version":[{"id":174650,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/posts\/174616\/revisions\/174650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/media\/174618"}],"wp:attachment":[{"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/media?parent=174616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/categories?post=174616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/tags?post=174616"},{"taxonomy":"wl_entity_type","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/wl_entity_type?post=174616"},{"taxonomy":"monatsauswahl","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/monatsauswahl?post=174616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}