{"id":144560,"date":"2020-05-22T06:27:32","date_gmt":"2020-05-22T04:27:32","guid":{"rendered":"https:\/\/www.salzburgerland.com\/de\/magazin\/?p=144560"},"modified":"2023-08-01T15:04:34","modified_gmt":"2023-08-01T13:04:34","slug":"das-salzburgerland-genusskisterl","status":"publish","type":"post","link":"https:\/\/www.salzburgerland.com\/de\/magazin\/das-salzburgerland-genusskisterl\/","title":{"rendered":"Das SalzburgerLand Genusskisterl"},"content":{"rendered":"\n<div class=\"wp-block-slt-top topBlocks\">\n<h2 class=\"wp-block-slt-subtitle\">\u2026 gef\u00fcllt mit kulinarischen Besonderheiten<\/h2>\n\n\n\n<p class=\"wp-block-slt-intro\">Einfach lecker was da alles in so einem SalzburgerLand Genusskisterl drinnen ist. Und auf jeden Fall garantiert regional und ausgezeichnet mit dem SalzburgerLand Herkunftssiegel.<\/p>\n<\/div>\n\n\n\n<p>Hurra \u2013 endlich ist es da, mein <a href=\"https:\/\/www.salzburgschmeckt.at\/salzburger-genuss-kisterl\" target=\"_blank\" rel=\"noreferrer noopener\">SalzburgerLand Genusskisterl<\/a>. Kaum bestellt und schon geliefert. Und das Allerbeste daran, alle diese K\u00f6stlichkeiten sind mit dem <a href=\"https:\/\/www.salzburgschmeckt.at\/salzburgerland-herkunfts-zertifikat\" target=\"_blank\" rel=\"noreferrer noopener\">SalzburgerLand Herkunfts-G\u00fctesiegel<\/a> ausgezeichnet. Und damit kann ich sicher sein, dass ich nur regional produzierte Lebensmittel auf dem Tisch habe.<\/p>\n\n\n\n<p>Jetzt hei\u00dft es aber gleich auspacken und schauen, welche kulinarischen Besonderheiten sich in meinem Kisterl verstecken.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-von-aroniabeeren-und-spanlingen\">Von Aroniabeeren und Sp\u00e4nlingen<\/h2>\n\n\n\n<p>Da f\u00e4llt mein Blick gleich als erstes auf den <strong>Bio Aronia Tee vom <a href=\"https:\/\/www.salzburgschmeckt.at\/betriebe\/zehnerhof-gottfried-rothensteiner\" target=\"_blank\" rel=\"noreferrer noopener\">Zehnerhof <\/a>in Mariapfarr<\/strong>. Aroniabeeren? Irgendwo schon einmal geh\u00f6rt, sollen sehr gesund und vitaminreich sein und eine wahre Rarit\u00e4t im Salzburger Lungau. Der Tee besteht jedenfalls aus getrockneten, gepressten und zerkleinerten Aroniabeeren, die dem Tee einen fruchtigen Geschmack und eine wunderbar dunkelrote Farbe verleihen.<\/p>\n\n\n\n<p>Und was ist das? Nudeln aus dem SalzburgerLand? Ja \u2013 auch die werden hier hergestellt. Konkret kommen die <strong>veganen Bio Vollkorn Dinkelnudeln<\/strong> im meiner Genusskiste vom <a href=\"https:\/\/www.biodinkelnudeln.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>St\u00f6cklbauer<\/strong><\/a> in St. Georgen. Sie werden aus der alten originalen Dinkelursorte \u201eOberkulmer (Ebners) Rotkorn&#8220; hergestellt und dank der schonenden Herstellung bleiben die wertvollen Inhaltsstoffe des Getreides weitgehend erhalten. Als Suppeneinlage, Beilage oder pur genossen \u2013 der Geschmack verspricht einzigartig zu sein.<\/p>\n\n\n\n<p><strong>Sp\u00e4nling<\/strong>? Noch nie geh\u00f6rt. Das Etikett auf <strong>dem Fruchtaufstrich des <a href=\"https:\/\/www.salzburgschmeckt.at\/betriebe\/stranzenhof-angelika-und-aegidius-leitner-eisl\" target=\"_blank\" rel=\"noreferrer noopener\">Stranzenhof<\/a><\/strong> in Thalgau kl\u00e4rt auf. Der &#8222;Sp\u00e4nling&#8220; ist die rote Zwetsckke, die in diesem Fall zu Marmelade verarbeitet wurde. Der Geschmack ist leicht s\u00e4uerlich und erinnert an Marillen. F\u00fcr den besonderen Geschmacks-Kick sorgt wahrscheinlich auch die traditionelle Einkochmethode am Holzofen.<\/p>\n\n\n\n<p>Neben der Marmelade liegt ein <strong>Bio-Camembert mit Rosmarin der <a href=\"https:\/\/www.salzburgschmeckt.at\/betriebe\/mattigtaler-kaese-familie-mangelberger\" target=\"_blank\" rel=\"noreferrer noopener\">Hofk\u00e4serei Mattigtaler<\/a><\/strong> in Seekirchen. Mhhh! Denn kenne ich schon und wei\u00df, wie weich und fein w\u00fcrzig er schmeckt.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1678\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste-.jpg\" alt=\"Eine Holzkiste, gef\u00fcllt mit verschiedenen Wurst- und K\u00e4sesorten, Brot, Marmeladen und Flaschen mit der Aufschrift Echtes Salzburger Genuss-Handwerk.\" class=\"wp-image-144561\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste-.jpg 1920w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste--300x262.jpg 300w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste--1536x1342.jpg 1536w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste--629x550.jpg 629w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste--458x400.jpg 458w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste--1320x1154.jpg 1320w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-salz-aus-dem-bergwerk\">Salz aus dem Bergwerk<\/h2>\n\n\n\n<p>Sass in Salzburg jahrhundertelang Salz abgebaut wurde, ist bekannt. Dass man aber auch heute noch <a href=\"https:\/\/www.salzburger-natursalz.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>handgesch\u00f6pftes Siedesalz aus Hallein<\/strong> <\/a>bekommen kann, \u00fcberrascht mich doch. Aber Tatsache \u2013 Familie Brudl hat sich des Erbes ihrer Heimatgemeinde angenommen. Sie bezieht die Salzsieder Sole aus dem Wolf-Dietrich-Stollen am D\u00fcrnberg und produziert daraus handgesch\u00f6pftes Siedesalz, unjodiert und ohne Rieselhilfe.<\/p>\n\n\n\n<p>Unglaublich ist die Farbintensit\u00e4t des <strong>Waldheidelbeersirups<\/strong> der <strong><a href=\"https:\/\/www.salzburgschmeckt.at\/betriebe\/obstpresse-leitner\" target=\"_blank\" rel=\"noreferrer noopener\">Obstpre<\/a><a href=\"https:\/\/www.salzburgschmeckt.at\/produkt\/waldheidelbeersirup\/\" target=\"_blank\" rel=\"noreferrer noopener\">sse Leitner<\/a> in Piesendorf<\/strong>. Mit nur wenigen Zutaten, n\u00e4mlich Waldheidelbeeren, Zucker (der tats\u00e4chlich ebenfalls aus \u00d6sterreich stammt), Wasser und Zitronens\u00e4ure entsteht ein erfrischend, fruchtiger Durstl\u00f6scher von einzigartigem Geschmack.<\/p>\n\n\n\n<p>Farblich um nichts nach steht dem Sirup die <strong>Rauriser Zirbe<\/strong> von Manuela Ellmauer aus Rauris. Der selbstgebrannte Apfelschnaps wird mit Zirbenzapfen angesetzt und\u00a0 in der Sonne gereift. Dadurch entsteht der leicht harzige Geschmack und die intensive rote F\u00e4rbung.<\/p>\n\n\n\n<p>F\u00fcr einen Farbtupfer sorgt schlie\u00dflich noch der <strong>duftende Basilikum<\/strong> vom <a href=\"https:\/\/www.salzburgschmeckt.at\/betriebe\/gartenbau-winkelhofer-johann-winklhofer\" target=\"_blank\" rel=\"noreferrer noopener\">Gartenbau Winkelhofer<\/a> in Wals.<\/p>\n\n\n\n<p>Bei dem Gedanken an die Bio Dinkelnudeln mit diesem frischen Basilikum meldet sich gleich mein knurrender Magen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-mit-liebe-und-leidenschaft-gemacht\">Mit Liebe und Leidenschaft gemacht<\/h2>\n\n\n\n<p>Unglaublich, welche Vielfalt an Lebensmitteln und Produkten es im SalzburgerLand so gibt. Da muss ich mich gar nicht erst lange \u00fcberzeugen lassen, regionale Produkte zu kaufen, denn die schmecken einfach noch besser \u2013 sind sie doch mit viel Liebe und Leidenschaft gemacht.<\/p>\n\n\n\n<p>\u00dcberzeugt euch doch gleich selbst. Hier findet ihr eine <a href=\"https:\/\/www.salzburgschmeckt.at\/salzburger-genuss-kisterl\" target=\"_blank\" rel=\"noreferrer noopener\">\u00dcbersicht aller H\u00e4ndler<\/a>, die das Genusskisterl nach pers\u00f6nlichen Vorlieben und Geschmack zusammenstellen.<\/p>\n\n\n\n<p>Und wenn ihr einmal auf der Suche nach einer originellen Geschenkidee sind \u2013 die Genusskiste gibt es auch als Geschenk-Edition.<\/p>\n\n\n\n<p>Lasst es euch schmecken!<\/p>\n\n\n<div class=\"mag-gallery\"><div class=\"row\"><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste5-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste5-325x209.jpg 325w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste5-249x160.jpg 249w\"><\/source><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste5-249x160.jpg 249w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste5-325x209.jpg 325w\"><\/source><img decoding=\"async\" alt=\"Holzgeschenkbox mit Marmelade, Honig, einem Glas Fruchtaufstrich und einer Flasche &Ouml;l auf Strohf&uuml;llung.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste5.jpg\">\t<\/picture><\/a><\/figure><\/div><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste2-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste2-325x209.jpg 325w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste2-249x160.jpg 249w\"><\/source><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste2-249x160.jpg 249w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste2-325x209.jpg 325w\"><\/source><img decoding=\"async\" alt=\"Eine h&ouml;lzerne Geschenkbox mit Nudeln, &Ouml;l, Marmelade, Tee und anderen Feinschmeckerartikeln mit Strohf&uuml;llung.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste2.jpg\">\t<\/picture><\/a><\/figure><\/div><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genuss-Kiste-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genuss-Kiste-325x209.jpg 325w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genuss-Kiste-249x160.jpg 249w\"><\/source><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genuss-Kiste-249x160.jpg 249w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genuss-Kiste-325x209.jpg 325w\"><\/source><img decoding=\"async\" alt=\"Geschenkbox aus Holz mit Nudeln, Honig, Marmelade, Sirup, Tee und Gew&uuml;rzen auf Strohf&uuml;llung.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genuss-Kiste.jpg\">\t<\/picture><\/a><\/figure><\/div><\/div><figcaption><\/figcaption><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hurra \u2013 endlich ist es da, mein SalzburgerLand Genusskisterl. Kaum bestellt und schon geliefert. Und das Allerbeste daran, alle diese K\u00f6stlichkeiten sind mit dem SalzburgerLand Herkunfts-G\u00fctesiegel ausgezeichnet. Und damit kann ich sicher sein, dass ich nur regional produzierte Lebensmittel auf dem Tisch habe. Jetzt hei\u00dft es aber gleich auspacken und schauen, welche kulinarischen Besonderheiten sich [&hellip;]<\/p>\n","protected":false},"author":90,"featured_media":144563,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wl_entities_gutenberg":"","_wl_entity_redirect_enabled":"","footnotes":""},"categories":[3],"tags":[],"wl_entity_type":[306],"monatsauswahl":[82,83,84,85,86,87,88,89,90,91,92,93],"class_list":["post-144560","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-essen-trinken","wl_entity_type-article","monatsauswahl-monat_1","monatsauswahl-monat_2","monatsauswahl-monat_3","monatsauswahl-monat_4","monatsauswahl-monat_5","monatsauswahl-monat_6","monatsauswahl-monat_7","monatsauswahl-monat_8","monatsauswahl-monat_9","monatsauswahl-monat_10","monatsauswahl-monat_11","monatsauswahl-monat_12"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Das SalzburgerLand Genusskisterl - SalzburgerLand Magazin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/das-salzburgerland-genusskisterl\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Das SalzburgerLand Genusskisterl\" \/>\n<meta property=\"og:description\" content=\"Hurra \u2013 endlich ist es da, mein SalzburgerLand Genusskisterl. Kaum bestellt und schon geliefert. Und das Allerbeste daran, alle diese K\u00f6stlichkeiten sind mit dem SalzburgerLand Herkunfts-G\u00fctesiegel ausgezeichnet. Und damit kann ich sicher sein, dass ich nur regional produzierte Lebensmittel auf dem Tisch habe. Jetzt hei\u00dft es aber gleich auspacken und schauen, welche kulinarischen Besonderheiten sich [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salzburgerland.com\/de\/magazin\/das-salzburgerland-genusskisterl\/\" \/>\n<meta property=\"og:site_name\" content=\"SalzburgerLand Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/salzburgerland\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-22T04:27:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-01T13:04:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1591\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ulli Hammerl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Salzburgerland\" \/>\n<meta name=\"twitter:site\" content=\"@Salzburgerland\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ulli Hammerl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/das-salzburgerland-genusskisterl\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/das-salzburgerland-genusskisterl\\\/\"},\"author\":{\"name\":\"Ulli Hammerl\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#\\\/schema\\\/person\\\/a55a4fee1009b9e458d298480a18a9f7\"},\"headline\":\"Das SalzburgerLand Genusskisterl\",\"datePublished\":\"2020-05-22T04:27:32+00:00\",\"dateModified\":\"2023-08-01T13:04:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/das-salzburgerland-genusskisterl\\\/\"},\"wordCount\":574,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/das-salzburgerland-genusskisterl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/SalzburgerLand-Genusskiste1.jpg\",\"articleSection\":[\"Essen &amp; Trinken\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/das-salzburgerland-genusskisterl\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/das-salzburgerland-genusskisterl\\\/\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/das-salzburgerland-genusskisterl\\\/\",\"name\":\"Das SalzburgerLand Genusskisterl - SalzburgerLand Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/das-salzburgerland-genusskisterl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/das-salzburgerland-genusskisterl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/SalzburgerLand-Genusskiste1.jpg\",\"datePublished\":\"2020-05-22T04:27:32+00:00\",\"dateModified\":\"2023-08-01T13:04:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/das-salzburgerland-genusskisterl\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/das-salzburgerland-genusskisterl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/das-salzburgerland-genusskisterl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/SalzburgerLand-Genusskiste1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/SalzburgerLand-Genusskiste1.jpg\",\"width\":1920,\"height\":1591,\"caption\":\"Holzkiste mit der Aufschrift Echtes Salzburger Genuss-Handwerk, gef\u00fcllt mit Gourmet-Lebensmitteln, Kr\u00e4utern und Nudeln.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/das-salzburgerland-genusskisterl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Essen &amp; Trinken\",\"item\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/thema\\\/essen-trinken\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Das SalzburgerLand Genusskisterl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/\",\"name\":\"SalzburgerLand Magazin\",\"description\":\"Geschichten und Interessantes aus dem SalzburgerLand\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#organization\",\"name\":\"SalzburgerLand Tourismus\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/salzburgerland-logo1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/salzburgerland-logo1.jpg\",\"width\":2011,\"height\":866,\"caption\":\"SalzburgerLand Tourismus\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/salzburgerland\\\/\",\"https:\\\/\\\/x.com\\\/Salzburgerland\",\"https:\\\/\\\/www.instagram.com\\\/salzburgerland\\\/\",\"https:\\\/\\\/at.linkedin.com\\\/company\\\/salzburgerland-tourismus-gmbh\",\"https:\\\/\\\/www.pinterest.at\\\/salzburgerland\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/salzburgerland\",\"https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/SalzburgerLand_Tourismus_GmbH\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#\\\/schema\\\/person\\\/a55a4fee1009b9e458d298480a18a9f7\",\"name\":\"Ulli Hammerl\",\"description\":\"Geboren und aufgewachsen in der Stadt Salzburg war Ulli Hammerl fr\u00fch bewusst, in einer der sch\u00f6nsten St\u00e4dte der Welt zu leben. So ist sie auch w\u00e4hrend ihres Studiums der Kommunikationswissenschaft und \u00d6kologie ihrer Heimatstadt treu geblieben. Gleich nach dem Studium ist sie zu SalzburgerLand Tourismus (SLTG) gegangen und hat hier von 1998 - 2004 u.a. die SalzburgerLand Card betreut. Dabei ist sie viel herumgekommen, wodurch auch die Liebe zum SalzburgerLand enstanden und gewachsen ist. Nach der Geburt ihrer Tochter im September 2004 hat sich Ulli Hammerl 2007 mit einer Agentur selbst\u00e4ndig gemacht. Mein pers\u00f6nlicher Logenplatz: Hoch \u00fcber Salzburg, abseits der stark begangenen Wege mit Blick auf die D\u00e4cher und Kircht\u00fcrme der Stadt \u2013 hier geht mir das Herz auf! Morgen- oder Abendmensch: Ganz klar: Morgenmensch. Wenn um 5.00 Uhr fr\u00fch die V\u00f6gel zwitschern und rund herum noch alles in tiefer Ruhe versinkt, dann ist meine Zeit. Ausgeschlafen, Energie geladen und voller Tatendrang starte ich am liebsten in den fr\u00fchen Morgenstunden in den Tag. Daf\u00fcr kann man nach 21.00 Uhr nicht mehr mit mir rechnen. Buch oder Film: Es gibt nichts Sch\u00f6neres, als es sich am Ende des Tages auf der Couch gem\u00fctlich zu machen und in die Gedankenwelt eines guten Buches einzutauchen \u2013 Lesen ist Abenteuer im Kopf. Wandern, Spazierengehen oder Laufen: alles drei und zwar am besten jeden Tag. Mit ein bisschen Zeiteinteilung geht es sich tats\u00e4chlich fast gehen Tag aus, drau\u00dfen unterwegs zu sein. Fr\u00fchling, Sommer, Herbst oder Winter: Ich kann es im Fr\u00fchling kaum erwarten, die ersten Gr\u00fcnschattierungen in der Natur zu entdecken. Ich liebe hei\u00dfe Sommertage am See und laue Sommerabende am Balkon. Ich mag es, wenn im Herbst die W\u00e4lder in einem Meer aus Farben erstrahlen, Laubrascheln und Kastanien sammeln. Und ich freue mich wie ein Kind, wenn im Dezember die ersten Schneeflocken vom Himmel schweben. Die vier Jahreszeiten sind etwas Wunderbares.\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/author\\\/ulli-hammerl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Das SalzburgerLand Genusskisterl - SalzburgerLand Magazin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salzburgerland.com\/de\/magazin\/das-salzburgerland-genusskisterl\/","og_locale":"de_DE","og_type":"article","og_title":"Das SalzburgerLand Genusskisterl","og_description":"Hurra \u2013 endlich ist es da, mein SalzburgerLand Genusskisterl. Kaum bestellt und schon geliefert. Und das Allerbeste daran, alle diese K\u00f6stlichkeiten sind mit dem SalzburgerLand Herkunfts-G\u00fctesiegel ausgezeichnet. Und damit kann ich sicher sein, dass ich nur regional produzierte Lebensmittel auf dem Tisch habe. Jetzt hei\u00dft es aber gleich auspacken und schauen, welche kulinarischen Besonderheiten sich [&hellip;]","og_url":"https:\/\/www.salzburgerland.com\/de\/magazin\/das-salzburgerland-genusskisterl\/","og_site_name":"SalzburgerLand Magazin","article_publisher":"https:\/\/www.facebook.com\/salzburgerland\/","article_published_time":"2020-05-22T04:27:32+00:00","article_modified_time":"2023-08-01T13:04:34+00:00","og_image":[{"width":1920,"height":1591,"url":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste1.jpg","type":"image\/jpeg"}],"author":"Ulli Hammerl","twitter_card":"summary_large_image","twitter_creator":"@Salzburgerland","twitter_site":"@Salzburgerland","twitter_misc":{"Verfasst von":"Ulli Hammerl","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/das-salzburgerland-genusskisterl\/#article","isPartOf":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/das-salzburgerland-genusskisterl\/"},"author":{"name":"Ulli Hammerl","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#\/schema\/person\/a55a4fee1009b9e458d298480a18a9f7"},"headline":"Das SalzburgerLand Genusskisterl","datePublished":"2020-05-22T04:27:32+00:00","dateModified":"2023-08-01T13:04:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/das-salzburgerland-genusskisterl\/"},"wordCount":574,"commentCount":0,"publisher":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#organization"},"image":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/das-salzburgerland-genusskisterl\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste1.jpg","articleSection":["Essen &amp; Trinken"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salzburgerland.com\/de\/magazin\/das-salzburgerland-genusskisterl\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/das-salzburgerland-genusskisterl\/","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/das-salzburgerland-genusskisterl\/","name":"Das SalzburgerLand Genusskisterl - SalzburgerLand Magazin","isPartOf":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/das-salzburgerland-genusskisterl\/#primaryimage"},"image":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/das-salzburgerland-genusskisterl\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste1.jpg","datePublished":"2020-05-22T04:27:32+00:00","dateModified":"2023-08-01T13:04:34+00:00","breadcrumb":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/das-salzburgerland-genusskisterl\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salzburgerland.com\/de\/magazin\/das-salzburgerland-genusskisterl\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/das-salzburgerland-genusskisterl\/#primaryimage","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste1.jpg","contentUrl":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2020\/05\/SalzburgerLand-Genusskiste1.jpg","width":1920,"height":1591,"caption":"Holzkiste mit der Aufschrift Echtes Salzburger Genuss-Handwerk, gef\u00fcllt mit Gourmet-Lebensmitteln, Kr\u00e4utern und Nudeln."},{"@type":"BreadcrumbList","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/das-salzburgerland-genusskisterl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.salzburgerland.com\/de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Essen &amp; Trinken","item":"https:\/\/www.salzburgerland.com\/de\/magazin\/thema\/essen-trinken\/"},{"@type":"ListItem","position":3,"name":"Das SalzburgerLand Genusskisterl"}]},{"@type":"WebSite","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#website","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/","name":"SalzburgerLand Magazin","description":"Geschichten und Interessantes aus dem SalzburgerLand","publisher":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salzburgerland.com\/de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#organization","name":"SalzburgerLand Tourismus","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#\/schema\/logo\/image\/","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2019\/06\/salzburgerland-logo1.jpg","contentUrl":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2019\/06\/salzburgerland-logo1.jpg","width":2011,"height":866,"caption":"SalzburgerLand Tourismus"},"image":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/salzburgerland\/","https:\/\/x.com\/Salzburgerland","https:\/\/www.instagram.com\/salzburgerland\/","https:\/\/at.linkedin.com\/company\/salzburgerland-tourismus-gmbh","https:\/\/www.pinterest.at\/salzburgerland\/","https:\/\/www.youtube.com\/user\/salzburgerland","https:\/\/de.wikipedia.org\/wiki\/SalzburgerLand_Tourismus_GmbH"]},{"@type":"Person","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#\/schema\/person\/a55a4fee1009b9e458d298480a18a9f7","name":"Ulli Hammerl","description":"Geboren und aufgewachsen in der Stadt Salzburg war Ulli Hammerl fr\u00fch bewusst, in einer der sch\u00f6nsten St\u00e4dte der Welt zu leben. So ist sie auch w\u00e4hrend ihres Studiums der Kommunikationswissenschaft und \u00d6kologie ihrer Heimatstadt treu geblieben. Gleich nach dem Studium ist sie zu SalzburgerLand Tourismus (SLTG) gegangen und hat hier von 1998 - 2004 u.a. die SalzburgerLand Card betreut. Dabei ist sie viel herumgekommen, wodurch auch die Liebe zum SalzburgerLand enstanden und gewachsen ist. Nach der Geburt ihrer Tochter im September 2004 hat sich Ulli Hammerl 2007 mit einer Agentur selbst\u00e4ndig gemacht. Mein pers\u00f6nlicher Logenplatz: Hoch \u00fcber Salzburg, abseits der stark begangenen Wege mit Blick auf die D\u00e4cher und Kircht\u00fcrme der Stadt \u2013 hier geht mir das Herz auf! Morgen- oder Abendmensch: Ganz klar: Morgenmensch. Wenn um 5.00 Uhr fr\u00fch die V\u00f6gel zwitschern und rund herum noch alles in tiefer Ruhe versinkt, dann ist meine Zeit. Ausgeschlafen, Energie geladen und voller Tatendrang starte ich am liebsten in den fr\u00fchen Morgenstunden in den Tag. Daf\u00fcr kann man nach 21.00 Uhr nicht mehr mit mir rechnen. Buch oder Film: Es gibt nichts Sch\u00f6neres, als es sich am Ende des Tages auf der Couch gem\u00fctlich zu machen und in die Gedankenwelt eines guten Buches einzutauchen \u2013 Lesen ist Abenteuer im Kopf. Wandern, Spazierengehen oder Laufen: alles drei und zwar am besten jeden Tag. Mit ein bisschen Zeiteinteilung geht es sich tats\u00e4chlich fast gehen Tag aus, drau\u00dfen unterwegs zu sein. Fr\u00fchling, Sommer, Herbst oder Winter: Ich kann es im Fr\u00fchling kaum erwarten, die ersten Gr\u00fcnschattierungen in der Natur zu entdecken. Ich liebe hei\u00dfe Sommertage am See und laue Sommerabende am Balkon. Ich mag es, wenn im Herbst die W\u00e4lder in einem Meer aus Farben erstrahlen, Laubrascheln und Kastanien sammeln. Und ich freue mich wie ein Kind, wenn im Dezember die ersten Schneeflocken vom Himmel schweben. Die vier Jahreszeiten sind etwas Wunderbares.","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/author\/ulli-hammerl\/"}]}},"_wl_alt_label":[],"wl:entity_url":"http:\/\/open.salzburgerland.com\/magazin\/post\/das_salzburgerland_genusskisterl","_links":{"self":[{"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/posts\/144560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/comments?post=144560"}],"version-history":[{"count":5,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/posts\/144560\/revisions"}],"predecessor-version":[{"id":172621,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/posts\/144560\/revisions\/172621"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/media\/144563"}],"wp:attachment":[{"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/media?parent=144560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/categories?post=144560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/tags?post=144560"},{"taxonomy":"wl_entity_type","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/wl_entity_type?post=144560"},{"taxonomy":"monatsauswahl","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/monatsauswahl?post=144560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}