{"id":103153,"date":"2015-11-12T18:00:12","date_gmt":"2015-11-12T17:00:12","guid":{"rendered":"http:\/\/magazin.salzburgerland.com\/?p=103153"},"modified":"2019-10-03T08:58:29","modified_gmt":"2019-10-03T06:58:29","slug":"der-murtalradweg-und-die-murtalbahn","status":"publish","type":"post","link":"https:\/\/www.salzburgerland.com\/de\/magazin\/der-murtalradweg-und-die-murtalbahn\/","title":{"rendered":"Der Murradweg und die Murtalbahn"},"content":{"rendered":"<p><strong>Im Bauernherbst, wenn die letzten Sonnenstrahlen unsere Gem\u00fcter erw\u00e4rmen und sich noch einmal\u00a0gegen die unweigerlich kommende K\u00e4lte des bevorstehenden Winters aufb\u00e4umen, ist es auch f\u00fcr uns Menschen an der Zeit, aktiv zu werden und diese Stunden so richtig auszunutzen. Warum schnappen Sie nicht Ihr Rad und begeben sich auf eine eint\u00e4gige Fahrt auf dem Murradweg entlang der Mur? Inmitten der herrlichen Landschaft des Lungaus und der bunten W\u00e4lder und entlang des glasklaren Flusses werden Sie einen Tag erleben, von dem Sie noch lange zehren werden k\u00f6nnen.\u00a0<\/strong><\/p>\n<p>Der <a href=\"https:\/\/www.lungau.at\/de\/aktiv\/sommerurlaub\/almsommer-bauernherbst\/rad-bike\/murradweg\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-wplink-edit=\"true\">Murradweg<\/a> gilt unter Kennern, als einer der sch\u00f6nsten Flussradwege im Alpenraum. Aufgrund seiner Vielfalt und der malerischen Landschaften, ist er f\u00fcr jeden Radfahrer garantiert ein Erlebnis. Begleitet wird er von der Murtalbahn, die sich ihren Weg, seit dem 08. Oktober 1894, durch die atemberaubende Berglandschaft bahnt. Die Schmalspurbahn bringt\u00a0Sie in nostalgischer Atmosph\u00e4re durch W\u00e4lder und Auen, entlang einer imposanten Gebirgskulisse und einer gr\u00fcnschimmernden Mur. \u00a0Der Fluss, der\u00a0im Salzburger Lungau entspringt und welcher durch die Steiermark bis hinunter zur slowenischen Grenze nach Bad Radkersburg flie\u00dft, ist einer der sch\u00f6nsten und saubersten Fl\u00fcsse unseres Landes und strahlt auf Einheimische und G\u00e4ste gleicherma\u00dfen eine besondere Ruhe aus.<\/p>\n<p>Die wunderbare Rad-Reise beginnt im Ortskern der kleinen und vertr\u00e4umten Ortschaft Muhr im Lungau, von wo Sie die erste Etappe des Murradweges durch die weitl\u00e4ufige und eindrucksvolle Beckenlandschaft des Lungaus meistern werden. Bereits zu Beginn der Tour, werden Sie von der Sch\u00f6nheit und der Vielf\u00e4lligkeit des Biosph\u00e4renparks Salzburger Lungau gefesselt sein. Die seit 2012 von der UNESCO ausgezeichnete Region, bietet Ihnen einen Raum, in dem ausgepr\u00e4gte Traditionen und eine abwechslungsreiche Naturlandschaft, zwischen dem Radst\u00e4dter im Norden und den Nockbergen im S\u00fcden eingebettet ist.<br \/>\nNach den ersten 25 Kilometern erreicht man die historische Ortschaft Tamsweg. Bekannt wurde diese durch die beeindruckende Wallfahrtskirche St. Leonhard, die bereits im Jahre 1231 urkundlich erw\u00e4hnt wurde und schon seit vielen Jahrhunderten ein wichtiger Ort des katholischen Glaubens ist. Auch zur Erholung bieten sich beste Gelegenheiten, wo Sie bei einer st\u00e4rkenden Jause neue Energie f\u00fcr die weitere Radtour sammeln k\u00f6nnen. Gut gest\u00e4rkt geht es dann weiter entlang des sprudelnden Flusses und entlang der gr\u00fcnen Wiesen. Lassen Sie die sch\u00f6ne Ortschaft Ramingstein mit der Burg Finstergr\u00fcn hinter sich, genie\u00dfen Sie die friedliche Stimmung am Weg und erreichen Sie schlie\u00dflich die steirische Ortschaft Kreischberg. Hier ist f\u00fcr viele Radler die Tagesetappe zu Ende und man kann endlich die mittlerweile m\u00fcden Beine ausruhen.<\/p>\n<p>Nachdem man bis hierhin aus eigener Kraft gekommen ist, hei\u00dft es nun\u00a0\u201eAlle Mann\u00a0einsteigen\u201c in die Murtalbahn, die einen entspannt wieder zur\u00fcck nach Tamsweg\u00a0bringt.\u00a0Auf dieser eindrucksvollen Bahnstrecke zwischen der Bezirkshauptstadt und Unzmarkt in der Steiermark, haben Sie die Chance, noch einmal die fesselnde Kraft der Berge zu sp\u00fcren und die wundersch\u00f6ne und vielf\u00e4ltige Natur der Region zu genie\u00dfen. Erleben Sie dabei eine entspannende Bahnfahrt bis es wieder hei\u00dft \u201eEndstation! Alles aussteigen!\u201c. Ein wunderbarer Tag naht sich dem Ende zu, doch als aufmerksamer Leser dieses Magazins wissen Sie nat\u00fcrlich, dass man auch Abends und vor allem kulinarisch, im Lungau noch so einiges erleben kann. In diesem Sinne w\u00fcnschen wir Ihnen einen wundersch\u00f6nen Radltag und w\u00fcrden uns freuen, wenn Sie Ihre Erfahrungen am Murradweg mit uns und den anderen Lesern teilen w\u00fcrden.<\/p>\n<p><strong>PS:<\/strong>\u00a0Sind Sie Liebhaber\u00a0historischer Eisenbahnen? Dann k\u00f6nnen Sie zwischen\u00a0Mauterndorf und St.\u00a0 Andr\u00e4 ein besonderes St\u00fcck Geschichte erleben und mit einer originalen Dampflok-Garnitur gem\u00fctlich durch den Lungau fahren. Infos zur so genannten Taurachbahn finden Sie <a href=\"http:\/\/www.club760.at\" target=\"_blank\" rel=\"noopener noreferrer\">hier<\/a>.<\/p>\n<div class=\"mag-gallery\"><div class=\"row\"><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murtalbahn2_Foto-GH-Saliterer-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murtalbahn2_Foto-GH-Saliterer-325x209.jpg 325w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murtalbahn2_Foto-GH-Saliterer-249x160.jpg 249w\" \/><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murtalbahn2_Foto-GH-Saliterer-249x160.jpg 249w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murtalbahn2_Foto-GH-Saliterer-325x209.jpg 325w\" \/><img decoding=\"async\" alt=\"Ein alter Dampfzug mit bunten Waggons f\u00e4hrt auf den Gleisen in einer gr\u00fcnen, bewaldeten Gegend.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murtalbahn2_Foto-GH-Saliterer.jpg\" \/>\t<\/picture><\/a><\/figure><\/div><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murtalbahn@GH-Saliterer-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murtalbahn@GH-Saliterer-325x209.jpg 325w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murtalbahn@GH-Saliterer-249x160.jpg 249w\" \/><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murtalbahn@GH-Saliterer-249x160.jpg 249w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murtalbahn@GH-Saliterer-325x209.jpg 325w\" \/><img decoding=\"async\" alt=\"Dampfzug mit der Aufschrift Murtalbahn mit einem Schaffner in Uniform, der neben dem Zug in einer l\u00e4ndlichen Gegend steht.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murtalbahn@GH-Saliterer.jpg\" \/>\t<\/picture><\/a><\/figure><\/div><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murtalbahn_Foto-GH-Saliterer-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murtalbahn_Foto-GH-Saliterer-325x209.jpg 325w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murtalbahn_Foto-GH-Saliterer-249x160.jpg 249w\" \/><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murtalbahn_Foto-GH-Saliterer-249x160.jpg 249w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murtalbahn_Foto-GH-Saliterer-325x209.jpg 325w\" \/><img decoding=\"async\" alt=\"Ein kleiner Dampfzug mit roten und gr\u00fcnen Waggons f\u00e4hrt an einem grasbewachsenen Feld mit B\u00e4umen im Hintergrund vorbei.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murtalbahn_Foto-GH-Saliterer.jpg\" \/>\t<\/picture><\/a><\/figure><\/div><\/div><\/div><figcaption><\/figcaption>\n<p>\u00a9alle Bilder: GH Saliterer; au\u00dfer Titelbild: TVB Muhr<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Bauernherbst, wenn die letzten Sonnenstrahlen unsere Gem\u00fcter erw\u00e4rmen und sich noch einmal\u00a0gegen die unweigerlich kommende K\u00e4lte des bevorstehenden Winters aufb\u00e4umen, ist es auch f\u00fcr uns Menschen an der Zeit, aktiv zu werden und diese Stunden so richtig auszunutzen. Warum schnappen Sie nicht Ihr Rad und begeben sich auf eine eint\u00e4gige Fahrt auf dem Murradweg [&hellip;]<\/p>\n","protected":false},"author":505,"featured_media":103172,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wl_entities_gutenberg":"","_wl_entity_redirect_enabled":"","footnotes":""},"categories":[8],"tags":[186],"wl_entity_type":[306],"monatsauswahl":[84,85,86,87,88,89,90,91,92],"class_list":["post-103153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-outdoor-sport","tag-bauernherbst","wl_entity_type-article","monatsauswahl-monat_3","monatsauswahl-monat_4","monatsauswahl-monat_5","monatsauswahl-monat_6","monatsauswahl-monat_7","monatsauswahl-monat_8","monatsauswahl-monat_9","monatsauswahl-monat_10","monatsauswahl-monat_11"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Der Murradweg und die Murtalbahn - SalzburgerLand Magazin<\/title>\n<meta name=\"description\" content=\"Im Bauernherbst, wenn die letzten Sonnenstrahlen unsere Gem\u00fcter erw\u00e4rmen und sich noch einmal\u00a0gegen die unweigerlich kommende K\u00e4lte des bevorstehenden Winters aufb\u00e4umen, ist es auch f\u00fcr uns Menschen an der Zeit, aktiv zu werden und diese Stunden so richtig auszunutzen. Warum schnappen Sie nicht Ihr Rad und begeben sich auf eine eint\u00e4gige Fahrt auf dem Murradweg [&hellip;]\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/der-murtalradweg-und-die-murtalbahn\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der Murradweg und die Murtalbahn\" \/>\n<meta property=\"og:description\" content=\"Im Bauernherbst, wenn die letzten Sonnenstrahlen unsere Gem\u00fcter erw\u00e4rmen und sich noch einmal\u00a0gegen die unweigerlich kommende K\u00e4lte des bevorstehenden Winters aufb\u00e4umen, ist es auch f\u00fcr uns Menschen an der Zeit, aktiv zu werden und diese Stunden so richtig auszunutzen. Warum schnappen Sie nicht Ihr Rad und begeben sich auf eine eint\u00e4gige Fahrt auf dem Murradweg [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salzburgerland.com\/de\/magazin\/der-murtalradweg-und-die-murtalbahn\/\" \/>\n<meta property=\"og:site_name\" content=\"SalzburgerLand Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/salzburgerland\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-12T17:00:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-03T06:58:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murradweg-Bildnachweis-TVB-Muhr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Peter Zeitlhofer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Salzburgerland\" \/>\n<meta name=\"twitter:site\" content=\"@Salzburgerland\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Peter Zeitlhofer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/der-murtalradweg-und-die-murtalbahn\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/der-murtalradweg-und-die-murtalbahn\\\/\"},\"author\":{\"name\":\"Peter Zeitlhofer\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#\\\/schema\\\/person\\\/ebd2c9f244aeea71e30f3b5d5e309de4\"},\"headline\":\"Der Murradweg und die Murtalbahn\",\"datePublished\":\"2015-11-12T17:00:12+00:00\",\"dateModified\":\"2019-10-03T06:58:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/der-murtalradweg-und-die-murtalbahn\\\/\"},\"wordCount\":632,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/der-murtalradweg-und-die-murtalbahn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/Murradweg-Bildnachweis-TVB-Muhr.jpg\",\"keywords\":[\"Bauernherbst\"],\"articleSection\":[\"Outdoor &amp; Sport\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/der-murtalradweg-und-die-murtalbahn\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/der-murtalradweg-und-die-murtalbahn\\\/\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/der-murtalradweg-und-die-murtalbahn\\\/\",\"name\":\"Der Murradweg und die Murtalbahn - SalzburgerLand Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/der-murtalradweg-und-die-murtalbahn\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/der-murtalradweg-und-die-murtalbahn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/Murradweg-Bildnachweis-TVB-Muhr.jpg\",\"datePublished\":\"2015-11-12T17:00:12+00:00\",\"dateModified\":\"2019-10-03T06:58:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/der-murtalradweg-und-die-murtalbahn\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/der-murtalradweg-und-die-murtalbahn\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/der-murtalradweg-und-die-murtalbahn\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/Murradweg-Bildnachweis-TVB-Muhr.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/Murradweg-Bildnachweis-TVB-Muhr.jpg\",\"width\":1600,\"height\":1200,\"caption\":\"Radfahrer fahren auf einem Weg an einem Fluss entlang, mit einer gr\u00fcnen Wiese und einer Holzh\u00fctte im Hintergrund.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/der-murtalradweg-und-die-murtalbahn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Outdoor &amp; Sport\",\"item\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/thema\\\/outdoor-sport\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Der Murradweg und die Murtalbahn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/\",\"name\":\"SalzburgerLand Magazin\",\"description\":\"Geschichten und Interessantes aus dem SalzburgerLand\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#organization\",\"name\":\"SalzburgerLand Tourismus\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/salzburgerland-logo1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/salzburgerland-logo1.jpg\",\"width\":2011,\"height\":866,\"caption\":\"SalzburgerLand Tourismus\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/salzburgerland\\\/\",\"https:\\\/\\\/x.com\\\/Salzburgerland\",\"https:\\\/\\\/www.instagram.com\\\/salzburgerland\\\/\",\"https:\\\/\\\/at.linkedin.com\\\/company\\\/salzburgerland-tourismus-gmbh\",\"https:\\\/\\\/www.pinterest.at\\\/salzburgerland\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/salzburgerland\",\"https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/SalzburgerLand_Tourismus_GmbH\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#\\\/schema\\\/person\\\/ebd2c9f244aeea71e30f3b5d5e309de4\",\"name\":\"Peter Zeitlhofer\",\"description\":\"'Von Neugier getrieben' - diese Worte kommen Peter Zeitlhofer wohl schon ziemlich nahe. Egal ob am Segelboot, im Tiefschnee, unterwegs in Stadt und Land, oder auf einer seinen vielen Reisen - er ist immer auf der Suche nach Neuem, nach dem Besonderen, probiert so ziemlich alles aus und liebt es, dar\u00fcber zu reden und zu berichten. Womit man auch schon fast bei seiner zweiten Leidenschaft w\u00e4re - dem Schreiben. Immer und \u00fcberall ausgestattet\u00a0mit seinem Notebook, hat der Salzburger, mit Wurzeln am Attersee, sein Office\u00a0im wahrsten Sinne des Wortes unterm Arm und k\u00f6nnte sich nichts besseres vorstellen, als die Geschichten dort zu erz\u00e4hlen, wo sie passieren. Fr\u00fchling, Sommer, Herbst oder Winter? Als Mensch der Extreme, mag ich auch bei den Jahreszeiten den Sommer und den Winter am liebsten. Obwohl nat\u00fcrlich auch der Fr\u00fchling seine Reize hat. Aber der Herbst? Rindsroulade vom Pinzgauer Biorind oder Saibling fangfrisch aus dem Fuschlsee? Immer diese Entscheidungen! Kann ich auch beides haben? Mundharmonika oder Stradivari? Weder noch - als Gitarrist k\u00f6nnte ich mit beiden Instrumenten nichts anfangen. Lederhose oder Smoking? Eindeutig Lederhose, die bei mir mittlerweile sogar den Einzug in den sommerlichen Alltag gefunden hat. Und der LederhosnDonnerstag ist \u00a0ohnehin Pflicht. Alpinski, Offpist oder Skitour? Hauptsache rauf auf den Berg! Was dann tats\u00e4chlich auf dem Programm steht ist zweitrangig. Nur so viel: wenn der Schnee passt, dann h\u00e4lt mich nichts oder niemand auf der Piste. Bergtour oder Seentour? F\u00fcr mich gibt es im Sommer nichts Sch\u00f6neres, als mit dem Segelboot auf unseren herrlichen Seen unterwegs zu sein. Also wenn ich die Wahl habe, dann nehme ich im Sommer die Berge h\u00f6chstens als Kulisse. Haubenlokal oder Ab-Hof-Laden? Auch hier nehme ich von beidem ein bisschen. Aber bei der Oma schmeckt's dann doch am besten.\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/author\\\/peter-zeitlhofer\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Der Murradweg und die Murtalbahn - SalzburgerLand Magazin","description":"Im Bauernherbst, wenn die letzten Sonnenstrahlen unsere Gem\u00fcter erw\u00e4rmen und sich noch einmal\u00a0gegen die unweigerlich kommende K\u00e4lte des bevorstehenden Winters aufb\u00e4umen, ist es auch f\u00fcr uns Menschen an der Zeit, aktiv zu werden und diese Stunden so richtig auszunutzen. Warum schnappen Sie nicht Ihr Rad und begeben sich auf eine eint\u00e4gige Fahrt auf dem Murradweg [&hellip;]","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salzburgerland.com\/de\/magazin\/der-murtalradweg-und-die-murtalbahn\/","og_locale":"de_DE","og_type":"article","og_title":"Der Murradweg und die Murtalbahn","og_description":"Im Bauernherbst, wenn die letzten Sonnenstrahlen unsere Gem\u00fcter erw\u00e4rmen und sich noch einmal\u00a0gegen die unweigerlich kommende K\u00e4lte des bevorstehenden Winters aufb\u00e4umen, ist es auch f\u00fcr uns Menschen an der Zeit, aktiv zu werden und diese Stunden so richtig auszunutzen. Warum schnappen Sie nicht Ihr Rad und begeben sich auf eine eint\u00e4gige Fahrt auf dem Murradweg [&hellip;]","og_url":"https:\/\/www.salzburgerland.com\/de\/magazin\/der-murtalradweg-und-die-murtalbahn\/","og_site_name":"SalzburgerLand Magazin","article_publisher":"https:\/\/www.facebook.com\/salzburgerland\/","article_published_time":"2015-11-12T17:00:12+00:00","article_modified_time":"2019-10-03T06:58:29+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murradweg-Bildnachweis-TVB-Muhr.jpg","type":"image\/jpeg"}],"author":"Peter Zeitlhofer","twitter_card":"summary_large_image","twitter_creator":"@Salzburgerland","twitter_site":"@Salzburgerland","twitter_misc":{"Verfasst von":"Peter Zeitlhofer","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/der-murtalradweg-und-die-murtalbahn\/#article","isPartOf":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/der-murtalradweg-und-die-murtalbahn\/"},"author":{"name":"Peter Zeitlhofer","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#\/schema\/person\/ebd2c9f244aeea71e30f3b5d5e309de4"},"headline":"Der Murradweg und die Murtalbahn","datePublished":"2015-11-12T17:00:12+00:00","dateModified":"2019-10-03T06:58:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/der-murtalradweg-und-die-murtalbahn\/"},"wordCount":632,"commentCount":0,"publisher":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#organization"},"image":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/der-murtalradweg-und-die-murtalbahn\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murradweg-Bildnachweis-TVB-Muhr.jpg","keywords":["Bauernherbst"],"articleSection":["Outdoor &amp; Sport"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salzburgerland.com\/de\/magazin\/der-murtalradweg-und-die-murtalbahn\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/der-murtalradweg-und-die-murtalbahn\/","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/der-murtalradweg-und-die-murtalbahn\/","name":"Der Murradweg und die Murtalbahn - SalzburgerLand Magazin","isPartOf":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/der-murtalradweg-und-die-murtalbahn\/#primaryimage"},"image":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/der-murtalradweg-und-die-murtalbahn\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murradweg-Bildnachweis-TVB-Muhr.jpg","datePublished":"2015-11-12T17:00:12+00:00","dateModified":"2019-10-03T06:58:29+00:00","breadcrumb":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/der-murtalradweg-und-die-murtalbahn\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salzburgerland.com\/de\/magazin\/der-murtalradweg-und-die-murtalbahn\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/der-murtalradweg-und-die-murtalbahn\/#primaryimage","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murradweg-Bildnachweis-TVB-Muhr.jpg","contentUrl":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/11\/Murradweg-Bildnachweis-TVB-Muhr.jpg","width":1600,"height":1200,"caption":"Radfahrer fahren auf einem Weg an einem Fluss entlang, mit einer gr\u00fcnen Wiese und einer Holzh\u00fctte im Hintergrund."},{"@type":"BreadcrumbList","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/der-murtalradweg-und-die-murtalbahn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.salzburgerland.com\/de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Outdoor &amp; Sport","item":"https:\/\/www.salzburgerland.com\/de\/magazin\/thema\/outdoor-sport\/"},{"@type":"ListItem","position":3,"name":"Der Murradweg und die Murtalbahn"}]},{"@type":"WebSite","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#website","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/","name":"SalzburgerLand Magazin","description":"Geschichten und Interessantes aus dem SalzburgerLand","publisher":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salzburgerland.com\/de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#organization","name":"SalzburgerLand Tourismus","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#\/schema\/logo\/image\/","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2019\/06\/salzburgerland-logo1.jpg","contentUrl":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2019\/06\/salzburgerland-logo1.jpg","width":2011,"height":866,"caption":"SalzburgerLand Tourismus"},"image":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/salzburgerland\/","https:\/\/x.com\/Salzburgerland","https:\/\/www.instagram.com\/salzburgerland\/","https:\/\/at.linkedin.com\/company\/salzburgerland-tourismus-gmbh","https:\/\/www.pinterest.at\/salzburgerland\/","https:\/\/www.youtube.com\/user\/salzburgerland","https:\/\/de.wikipedia.org\/wiki\/SalzburgerLand_Tourismus_GmbH"]},{"@type":"Person","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#\/schema\/person\/ebd2c9f244aeea71e30f3b5d5e309de4","name":"Peter Zeitlhofer","description":"'Von Neugier getrieben' - diese Worte kommen Peter Zeitlhofer wohl schon ziemlich nahe. Egal ob am Segelboot, im Tiefschnee, unterwegs in Stadt und Land, oder auf einer seinen vielen Reisen - er ist immer auf der Suche nach Neuem, nach dem Besonderen, probiert so ziemlich alles aus und liebt es, dar\u00fcber zu reden und zu berichten. Womit man auch schon fast bei seiner zweiten Leidenschaft w\u00e4re - dem Schreiben. Immer und \u00fcberall ausgestattet\u00a0mit seinem Notebook, hat der Salzburger, mit Wurzeln am Attersee, sein Office\u00a0im wahrsten Sinne des Wortes unterm Arm und k\u00f6nnte sich nichts besseres vorstellen, als die Geschichten dort zu erz\u00e4hlen, wo sie passieren. Fr\u00fchling, Sommer, Herbst oder Winter? Als Mensch der Extreme, mag ich auch bei den Jahreszeiten den Sommer und den Winter am liebsten. Obwohl nat\u00fcrlich auch der Fr\u00fchling seine Reize hat. Aber der Herbst? Rindsroulade vom Pinzgauer Biorind oder Saibling fangfrisch aus dem Fuschlsee? Immer diese Entscheidungen! Kann ich auch beides haben? Mundharmonika oder Stradivari? Weder noch - als Gitarrist k\u00f6nnte ich mit beiden Instrumenten nichts anfangen. Lederhose oder Smoking? Eindeutig Lederhose, die bei mir mittlerweile sogar den Einzug in den sommerlichen Alltag gefunden hat. Und der LederhosnDonnerstag ist \u00a0ohnehin Pflicht. Alpinski, Offpist oder Skitour? Hauptsache rauf auf den Berg! Was dann tats\u00e4chlich auf dem Programm steht ist zweitrangig. Nur so viel: wenn der Schnee passt, dann h\u00e4lt mich nichts oder niemand auf der Piste. Bergtour oder Seentour? F\u00fcr mich gibt es im Sommer nichts Sch\u00f6neres, als mit dem Segelboot auf unseren herrlichen Seen unterwegs zu sein. Also wenn ich die Wahl habe, dann nehme ich im Sommer die Berge h\u00f6chstens als Kulisse. Haubenlokal oder Ab-Hof-Laden? Auch hier nehme ich von beidem ein bisschen. Aber bei der Oma schmeckt's dann doch am besten.","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/author\/peter-zeitlhofer\/"}]}},"_wl_alt_label":[],"wl:entity_url":"http:\/\/open.salzburgerland.com\/magazin\/post\/der_murradweg_und_die_murtalbahn","_links":{"self":[{"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/posts\/103153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/users\/505"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/comments?post=103153"}],"version-history":[{"count":0,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/posts\/103153\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/media\/103172"}],"wp:attachment":[{"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/media?parent=103153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/categories?post=103153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/tags?post=103153"},{"taxonomy":"wl_entity_type","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/wl_entity_type?post=103153"},{"taxonomy":"monatsauswahl","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/monatsauswahl?post=103153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}