{"id":100622,"date":"2015-08-11T12:00:35","date_gmt":"2015-08-11T10:00:35","guid":{"rendered":"http:\/\/magazin.salzburgerland.com\/?p=100622"},"modified":"2016-12-18T12:38:08","modified_gmt":"2016-12-18T11:38:08","slug":"salzburger-waldsalz-aus-untereggs-kraeutergartl","status":"publish","type":"post","link":"https:\/\/www.salzburgerland.com\/de\/magazin\/salzburger-waldsalz-aus-untereggs-kraeutergartl\/","title":{"rendered":"Salzburger Waldsalz aus Unteregg`s Kr\u00e4utergartl"},"content":{"rendered":"<p><strong>Kr\u00e4uterexpertin Christine Brunnauer arbeitet am liebsten mit Bl\u00fcten, Bl\u00e4ttern und Wurzeln. In ihrem \u00fcppig bl\u00fchenden Garten findet sie alles was ihre Familie braucht, um gesund zu bleiben. <br \/><\/strong><\/p>\n<p>Die bunte Kr\u00e4uterbutter auf frisch gebackenem Brot schmeckt k\u00f6stlich. Christine Brunnauer, ihres Zeichens <a href=\"http:\/\/www.teh.at\/\" target=\"_blank\">Praktikerin der Traditionell Europ\u00e4ischen Heilkunde (TEH) <\/a>und Naturapothekenabsolventin hat sie selbst gemacht. Dazu nimmt die Tennengauerin weiche Butter sowie Bl\u00fctenbl\u00e4tter von der orangen Ringelblume, dem hellblauen Borretsch und der blauen Kornblume. F\u00fcr diese Butter verwendet die <a href=\"http:\/\/untereggs-kraeutergartl.at\/\">B\u00e4uerin vom Unteregghof <\/a>nur Kr\u00e4uter die gerade in ihrem Garten oder auf der Wiese bl\u00fchen. &#8222;Im Sommer kann ich aus dem Vollen sch\u00f6pfen&#8220;, sagt sie strahlend. Im Fr\u00fchling gibt Brunnauer unter anderen L\u00f6wenzahn, G\u00e4nsebl\u00fcmchen und Veilchen in die Bl\u00fctenbutter. &#8222;Kinder und Erwachsene lieben diese Butter gleicherma\u00dfen&#8220;, sagt sie lachend.<\/p>\n<p>Auch die gr\u00fcnen Zutaten f\u00fcr das Salzburger Waldsalz erntet Brunnauer im Fr\u00fchling. Es vereint den Geschmack von Maiwipfeln (Fichte und Tanne), Engelwurz, Brennnessel und Oswegokraut zu einem harmonisch-w\u00fcrzigen Ganzen. Das Salzburger Waldsalz ist \u00fcbrigens eine Initiative von <a href=\"https:\/\/www.salzburgerland.com\/\" target=\"_blank\">Salzburger Land Tourismus,<\/a> <a href=\"http:\/\/www.salinen.com\/\" target=\"_blank\">Salinen Austria<\/a>, Unteregg&#8217;s Kr\u00e4utergartl und TEH Naturwerke. Brunnauer verkauft das Salzburger Waldsalz auf ihrem Biobauernhof, in der <a href=\"http:\/\/www.biokas.at\/\" target=\"_blank\">K\u00e4serei P\u00f6tzelsberger in Adnet<\/a> und im TEH-Gesch\u00e4ft in Unken.<\/p>\n<p><strong>Jeder entscheidet selbst was ihm gut tut<br \/><\/strong>Au\u00dfer Waldsalz stellt Brunnauer unter anderen Tinkturen, Seifen, Salben, Kr\u00e4uteressige und Schn\u00e4pse her. Bevor ihre Kundinnen und Kunden bei ihr kaufen, ber\u00e4t sie diese \u00fcber die Wirkung des Produktes. Dabei ist ihr wichtig, dass die Menschen selbst Verantwortung f\u00fcr die eigene Gesundheit \u00fcbernehmen. &#8222;Nicht jedes Kraut passt f\u00fcr jeden. Jeder entscheidet f\u00fcr sich selbst, was gut tut&#8220;, betont sie.<\/p>\n<p>Brunnauer ist \u00fcberzeugt, dass alles, was die Familie braucht, um das Haus w\u00e4chst. Ihr Kr\u00e4utergarten ist liebevoll angelegt. Im Sommer bl\u00fchen Minzearten, Frauenmantel und Eisenkraut. Brunnauer werkt gerne im Garten: &#8222;Diese Arbeit entspannt mich. Es macht Freude und Sinn, zu sehen wie alles w\u00e4chst und ich es zu gesunden Produkten verarbeiten kann.&#8220;<\/p>\n<div class=\"mag-gallery\"><div class=\"row\"><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-g-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-g-325x209.jpg 325w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-g-249x160.jpg 249w\" \/><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-g-249x160.jpg 249w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-g-325x209.jpg 325w\" \/><img decoding=\"async\" alt=\"Hinter einem \u00fcppigen Garten mit Steintreppen, Wildpflanzen und einem alten Wagenrad steht ein rustikales Haus.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-g.jpg\" \/>\t<\/picture><\/a><\/figure><\/div><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-c-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-c-325x209.jpg 325w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-c-249x160.jpg 249w\" \/><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-c-249x160.jpg 249w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-c-325x209.jpg 325w\" \/><img decoding=\"async\" alt=\"Ein \u00fcppiger Garten mit bunten Blumen und Pflanzen, Berge und ein bew\u00f6lkter Himmel im Hintergrund.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-c.jpg\" \/>\t<\/picture><\/a><\/figure><\/div><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-d-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-d-325x209.jpg 325w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-d-249x160.jpg 249w\" \/><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-d-249x160.jpg 249w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-d-325x209.jpg 325w\" \/><img decoding=\"async\" alt=\"Eine Frau sitzt auf einer H\u00e4ngematte in einem Garten mit Wildblumen, einem Holzstapel und einer malerischen Landschaft im Hintergrund.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-d.jpg\" \/>\t<\/picture><\/a><\/figure><\/div><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-e-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"\" \/><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-e.jpg 1019w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-e-256x300.jpg 256w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-e-470x550.jpg 470w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-e-342x400.jpg 342w\" \/><img decoding=\"async\" alt=\"Ein Schild zur F\u00f6rderung der biologischen Vielfalt in der Landwirtschaft mit farbigen Abbildungen von Pflanzen, Insekten und Tieren.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-e.jpg\" \/>\t<\/picture><\/a><\/figure><\/div><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-f-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-f-325x209.jpg 325w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-f-249x160.jpg 249w\" \/><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-f-249x160.jpg 249w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-f-325x209.jpg 325w\" \/><img decoding=\"async\" alt=\"Rustikales Schild mit Schneckenlogo und Text in einem Garten, mit Bergen und Gr\u00fcnzeug im Hintergrund.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-f.jpg\" \/>\t<\/picture><\/a><\/figure><\/div><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-a-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-a-325x209.jpg 325w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-a-249x160.jpg 249w\" \/><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-a-249x160.jpg 249w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-a-325x209.jpg 325w\" \/><img decoding=\"async\" alt=\"L\u00e4chelnde Frau mit kurzen Haaren, die in einem Garten mit Gr\u00fcnpflanzen und Holzstrukturen im Hintergrund steht.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-a.jpg\" \/>\t<\/picture><\/a><\/figure><\/div><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-b-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-b-325x209.jpg 325w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-b-249x160.jpg 249w\" \/><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-b-249x160.jpg 249w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-b-325x209.jpg 325w\" \/><img decoding=\"async\" alt=\"Eine Biene sammelt Nektar aus einem B\u00fcschel leuchtend gelber Bl\u00fcten, die von gr\u00fcnem Laub umgeben sind.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-b.jpg\" \/>\t<\/picture><\/a><\/figure><\/div><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-j-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-j-325x209.jpg 325w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-j-249x160.jpg 249w\" \/><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-j-249x160.jpg 249w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-j-325x209.jpg 325w\" \/><img decoding=\"async\" alt=\"Eine leuchtend rosa bl\u00fchende Rose mit gr\u00fcnen Bl\u00e4ttern und Knospen vor einem verschwommenen braunen und blaugr\u00fcnen Hintergrund.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-j.jpg\" \/>\t<\/picture><\/a><\/figure><\/div><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-i-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-i-325x209.jpg 325w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-i-249x160.jpg 249w\" \/><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-i-249x160.jpg 249w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-i-325x209.jpg 325w\" \/><img decoding=\"async\" alt=\"Leuchtend gelbe Wildblumen mit d\u00fcnnen Bl\u00fctenbl\u00e4ttern und gr\u00fcnen Bl\u00e4ttern, mit einer Biene auf einer der Bl\u00fcten.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-i.jpg\" \/>\t<\/picture><\/a><\/figure><\/div><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-h-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-h-325x209.jpg 325w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-h-249x160.jpg 249w\" \/><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-h-249x160.jpg 249w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-h-325x209.jpg 325w\" \/><img decoding=\"async\" alt=\"Glasgef\u00e4\u00df mit einem Metallverschluss mit der Aufschrift TEH Salzburger Wald Salz auf einer gewebten Oberfl\u00e4che.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-h.jpg\" \/>\t<\/picture><\/a><\/figure><\/div><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Unteregg-a-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Unteregg-a-325x209.jpg 325w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Unteregg-a-249x160.jpg 249w\" \/><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Unteregg-a-249x160.jpg 249w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Unteregg-a-325x209.jpg 325w\" \/><img decoding=\"async\" alt=\"Ein Teller mit Kr\u00e4uterbutter, garniert mit essbaren Bl\u00fcten, serviert mit Scheiben von Schwarzbrot.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Unteregg-a.jpg\" \/>\t<\/picture><\/a><\/figure><\/div><div class=\"col-6 col-sm-4\"><figure><a class=\"thumb-container\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauerm-1280x1024.jpg\">\t<picture><source media=\"(min-width: 576px)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauerm-325x209.jpg 325w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauerm-249x160.jpg 249w\" \/><source media=\"(min-width: 0)\" srcset=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauerm-249x160.jpg 249w, https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauerm-325x209.jpg 325w\" \/><img decoding=\"async\" alt=\"Eine l\u00e4chelnde Frau steht in einem \u00fcppigen Garten vor einem rustikalen Haus mit Holzakzenten und Balkonen.\" src=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauerm.jpg\" \/>\t<\/picture><\/a><\/figure><\/div><\/div><\/div><figcaption><\/figcaption>\n","protected":false},"excerpt":{"rendered":"<p>Kr\u00e4uterexpertin Christine Brunnauer arbeitet am liebsten mit Bl\u00fcten, Bl\u00e4ttern und Wurzeln. In ihrem \u00fcppig bl\u00fchenden Garten findet sie alles was ihre Familie braucht, um gesund zu bleiben. Die bunte Kr\u00e4uterbutter auf frisch gebackenem Brot schmeckt k\u00f6stlich. Christine Brunnauer, ihres Zeichens Praktikerin der Traditionell Europ\u00e4ischen Heilkunde (TEH) und Naturapothekenabsolventin hat sie selbst gemacht. Dazu nimmt die [&hellip;]<\/p>\n","protected":false},"author":236,"featured_media":100626,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wl_entities_gutenberg":"","_wl_entity_redirect_enabled":"","footnotes":""},"categories":[4],"tags":[],"wl_entity_type":[306],"monatsauswahl":[82,83,84,85,86,87,88,89,90,91,92,93],"class_list":["post-100622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesundheit","wl_entity_type-article","monatsauswahl-monat_1","monatsauswahl-monat_2","monatsauswahl-monat_3","monatsauswahl-monat_4","monatsauswahl-monat_5","monatsauswahl-monat_6","monatsauswahl-monat_7","monatsauswahl-monat_8","monatsauswahl-monat_9","monatsauswahl-monat_10","monatsauswahl-monat_11","monatsauswahl-monat_12"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Salzburger Waldsalz aus Unteregg`s Kr\u00e4utergartl - SalzburgerLand Magazin<\/title>\n<meta name=\"description\" content=\"Kr\u00e4uterexpertin Christine Brunnauer arbeitet am liebsten mit Bl\u00fcten, Bl\u00e4ttern und Wurzeln. In ihrem \u00fcppig bl\u00fchenden Garten findet sie alles was ihre Familie braucht, um gesund zu bleiben. Die bunte Kr\u00e4uterbutter auf frisch gebackenem Brot schmeckt k\u00f6stlich. Christine Brunnauer, ihres Zeichens Praktikerin der Traditionell Europ\u00e4ischen Heilkunde (TEH) und Naturapothekenabsolventin hat sie selbst gemacht. Dazu nimmt die [&hellip;]\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salzburgerland.com\/de\/magazin\/salzburger-waldsalz-aus-untereggs-kraeutergartl\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salzburger Waldsalz aus Unteregg`s Kr\u00e4utergartl\" \/>\n<meta property=\"og:description\" content=\"Kr\u00e4uterexpertin Christine Brunnauer arbeitet am liebsten mit Bl\u00fcten, Bl\u00e4ttern und Wurzeln. In ihrem \u00fcppig bl\u00fchenden Garten findet sie alles was ihre Familie braucht, um gesund zu bleiben. Die bunte Kr\u00e4uterbutter auf frisch gebackenem Brot schmeckt k\u00f6stlich. Christine Brunnauer, ihres Zeichens Praktikerin der Traditionell Europ\u00e4ischen Heilkunde (TEH) und Naturapothekenabsolventin hat sie selbst gemacht. Dazu nimmt die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salzburgerland.com\/de\/magazin\/salzburger-waldsalz-aus-untereggs-kraeutergartl\/\" \/>\n<meta property=\"og:site_name\" content=\"SalzburgerLand Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/salzburgerland\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-11T10:00:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-18T11:38:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1148\" \/>\n\t<meta property=\"og:image:height\" content=\"760\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christine Fr\u00f6schl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Salzburgerland\" \/>\n<meta name=\"twitter:site\" content=\"@Salzburgerland\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christine Fr\u00f6schl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/salzburger-waldsalz-aus-untereggs-kraeutergartl\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/salzburger-waldsalz-aus-untereggs-kraeutergartl\\\/\"},\"author\":{\"name\":\"Christine Fr\u00f6schl\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#\\\/schema\\\/person\\\/7932db74f19d9640620859cb2b794c4e\"},\"headline\":\"Salzburger Waldsalz aus Unteregg`s Kr\u00e4utergartl\",\"datePublished\":\"2015-08-11T10:00:35+00:00\",\"dateModified\":\"2016-12-18T11:38:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/salzburger-waldsalz-aus-untereggs-kraeutergartl\\\/\"},\"wordCount\":360,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/salzburger-waldsalz-aus-untereggs-kraeutergartl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/Christine-Brunnauer-d.jpg\",\"articleSection\":[\"Gesundheit\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/salzburger-waldsalz-aus-untereggs-kraeutergartl\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/salzburger-waldsalz-aus-untereggs-kraeutergartl\\\/\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/salzburger-waldsalz-aus-untereggs-kraeutergartl\\\/\",\"name\":\"Salzburger Waldsalz aus Unteregg`s Kr\u00e4utergartl - SalzburgerLand Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/salzburger-waldsalz-aus-untereggs-kraeutergartl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/salzburger-waldsalz-aus-untereggs-kraeutergartl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/Christine-Brunnauer-d.jpg\",\"datePublished\":\"2015-08-11T10:00:35+00:00\",\"dateModified\":\"2016-12-18T11:38:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/salzburger-waldsalz-aus-untereggs-kraeutergartl\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/salzburger-waldsalz-aus-untereggs-kraeutergartl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/salzburger-waldsalz-aus-untereggs-kraeutergartl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/Christine-Brunnauer-d.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/Christine-Brunnauer-d.jpg\",\"width\":1148,\"height\":760,\"caption\":\"Ausruhen in der H\u00e4ngematte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/salzburger-waldsalz-aus-untereggs-kraeutergartl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gesundheit\",\"item\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/thema\\\/gesundheit\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Salzburger Waldsalz aus Unteregg`s Kr\u00e4utergartl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/\",\"name\":\"SalzburgerLand Magazin\",\"description\":\"Geschichten und Interessantes aus dem SalzburgerLand\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#organization\",\"name\":\"SalzburgerLand Tourismus\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/salzburgerland-logo1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/salzburgerland-logo1.jpg\",\"width\":2011,\"height\":866,\"caption\":\"SalzburgerLand Tourismus\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/salzburgerland\\\/\",\"https:\\\/\\\/x.com\\\/Salzburgerland\",\"https:\\\/\\\/www.instagram.com\\\/salzburgerland\\\/\",\"https:\\\/\\\/at.linkedin.com\\\/company\\\/salzburgerland-tourismus-gmbh\",\"https:\\\/\\\/www.pinterest.at\\\/salzburgerland\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/salzburgerland\",\"https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/SalzburgerLand_Tourismus_GmbH\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/#\\\/schema\\\/person\\\/7932db74f19d9640620859cb2b794c4e\",\"name\":\"Christine Fr\u00f6schl\",\"description\":\"Dein pers\u00f6nlicher Logenplatz im SalzburgerLand? Am liebsten gehe ich auf den Einberg im Salzburger Tennengau. Der Berg in der Osterhorn-Gruppe gl\u00e4nzt das ganze Jahr im Sonnenschein, auf dem Gipfel heben Paragleiter ab und die Aussicht auf das Tennengebirge, den Dachstein und die Bischofsm\u00fctze ist traumhaft. Dosige(r) oder Zuagroast? Zuagroast aus dem sch\u00f6nen Nieder\u00f6sterreich. Fr\u00fchling, Sommer, Herbst oder Winter? Alle Jahreszeiten begeistern mich. Momentan freue ich mich auf den Fr\u00fchling, das Zwitschern der V\u00f6gel und auf die sattgr\u00fcnen Wiesen. Salzburger Nockerl oder Schwarzbeernocken? Eindeutig Schwarzbeernocken. Rindsroulade vom Pinzgauer Biorind oder Saibling fangfrisch aus dem Fuschlsee? Mhhhh. Da kann ich mich nicht entscheiden. Bergtour oder Seentour? Mich zieht es auf jeden Fall hinauf. Begeistert bin ich auch von tiefblauen Bergseen in denen sich die Umgebung spiegelt und von der Aussicht w\u00e4hrend des Weges auf einen der wundersch\u00f6nen Seen im Salzburger Land.\",\"url\":\"https:\\\/\\\/www.salzburgerland.com\\\/de\\\/magazin\\\/author\\\/christine-froeschl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Salzburger Waldsalz aus Unteregg`s Kr\u00e4utergartl - SalzburgerLand Magazin","description":"Kr\u00e4uterexpertin Christine Brunnauer arbeitet am liebsten mit Bl\u00fcten, Bl\u00e4ttern und Wurzeln. In ihrem \u00fcppig bl\u00fchenden Garten findet sie alles was ihre Familie braucht, um gesund zu bleiben. Die bunte Kr\u00e4uterbutter auf frisch gebackenem Brot schmeckt k\u00f6stlich. Christine Brunnauer, ihres Zeichens Praktikerin der Traditionell Europ\u00e4ischen Heilkunde (TEH) und Naturapothekenabsolventin hat sie selbst gemacht. Dazu nimmt die [&hellip;]","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salzburgerland.com\/de\/magazin\/salzburger-waldsalz-aus-untereggs-kraeutergartl\/","og_locale":"de_DE","og_type":"article","og_title":"Salzburger Waldsalz aus Unteregg`s Kr\u00e4utergartl","og_description":"Kr\u00e4uterexpertin Christine Brunnauer arbeitet am liebsten mit Bl\u00fcten, Bl\u00e4ttern und Wurzeln. In ihrem \u00fcppig bl\u00fchenden Garten findet sie alles was ihre Familie braucht, um gesund zu bleiben. Die bunte Kr\u00e4uterbutter auf frisch gebackenem Brot schmeckt k\u00f6stlich. Christine Brunnauer, ihres Zeichens Praktikerin der Traditionell Europ\u00e4ischen Heilkunde (TEH) und Naturapothekenabsolventin hat sie selbst gemacht. Dazu nimmt die [&hellip;]","og_url":"https:\/\/www.salzburgerland.com\/de\/magazin\/salzburger-waldsalz-aus-untereggs-kraeutergartl\/","og_site_name":"SalzburgerLand Magazin","article_publisher":"https:\/\/www.facebook.com\/salzburgerland\/","article_published_time":"2015-08-11T10:00:35+00:00","article_modified_time":"2016-12-18T11:38:08+00:00","og_image":[{"width":1148,"height":760,"url":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-d.jpg","type":"image\/jpeg"}],"author":"Christine Fr\u00f6schl","twitter_card":"summary_large_image","twitter_creator":"@Salzburgerland","twitter_site":"@Salzburgerland","twitter_misc":{"Verfasst von":"Christine Fr\u00f6schl","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/salzburger-waldsalz-aus-untereggs-kraeutergartl\/#article","isPartOf":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/salzburger-waldsalz-aus-untereggs-kraeutergartl\/"},"author":{"name":"Christine Fr\u00f6schl","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#\/schema\/person\/7932db74f19d9640620859cb2b794c4e"},"headline":"Salzburger Waldsalz aus Unteregg`s Kr\u00e4utergartl","datePublished":"2015-08-11T10:00:35+00:00","dateModified":"2016-12-18T11:38:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/salzburger-waldsalz-aus-untereggs-kraeutergartl\/"},"wordCount":360,"commentCount":0,"publisher":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#organization"},"image":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/salzburger-waldsalz-aus-untereggs-kraeutergartl\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-d.jpg","articleSection":["Gesundheit"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salzburgerland.com\/de\/magazin\/salzburger-waldsalz-aus-untereggs-kraeutergartl\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/salzburger-waldsalz-aus-untereggs-kraeutergartl\/","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/salzburger-waldsalz-aus-untereggs-kraeutergartl\/","name":"Salzburger Waldsalz aus Unteregg`s Kr\u00e4utergartl - SalzburgerLand Magazin","isPartOf":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/salzburger-waldsalz-aus-untereggs-kraeutergartl\/#primaryimage"},"image":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/salzburger-waldsalz-aus-untereggs-kraeutergartl\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-d.jpg","datePublished":"2015-08-11T10:00:35+00:00","dateModified":"2016-12-18T11:38:08+00:00","breadcrumb":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/salzburger-waldsalz-aus-untereggs-kraeutergartl\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salzburgerland.com\/de\/magazin\/salzburger-waldsalz-aus-untereggs-kraeutergartl\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/salzburger-waldsalz-aus-untereggs-kraeutergartl\/#primaryimage","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-d.jpg","contentUrl":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2015\/08\/Christine-Brunnauer-d.jpg","width":1148,"height":760,"caption":"Ausruhen in der H\u00e4ngematte"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/salzburger-waldsalz-aus-untereggs-kraeutergartl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.salzburgerland.com\/de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Gesundheit","item":"https:\/\/www.salzburgerland.com\/de\/magazin\/thema\/gesundheit\/"},{"@type":"ListItem","position":3,"name":"Salzburger Waldsalz aus Unteregg`s Kr\u00e4utergartl"}]},{"@type":"WebSite","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#website","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/","name":"SalzburgerLand Magazin","description":"Geschichten und Interessantes aus dem SalzburgerLand","publisher":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salzburgerland.com\/de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#organization","name":"SalzburgerLand Tourismus","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#\/schema\/logo\/image\/","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2019\/06\/salzburgerland-logo1.jpg","contentUrl":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-content\/uploads\/2019\/06\/salzburgerland-logo1.jpg","width":2011,"height":866,"caption":"SalzburgerLand Tourismus"},"image":{"@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/salzburgerland\/","https:\/\/x.com\/Salzburgerland","https:\/\/www.instagram.com\/salzburgerland\/","https:\/\/at.linkedin.com\/company\/salzburgerland-tourismus-gmbh","https:\/\/www.pinterest.at\/salzburgerland\/","https:\/\/www.youtube.com\/user\/salzburgerland","https:\/\/de.wikipedia.org\/wiki\/SalzburgerLand_Tourismus_GmbH"]},{"@type":"Person","@id":"https:\/\/www.salzburgerland.com\/de\/magazin\/#\/schema\/person\/7932db74f19d9640620859cb2b794c4e","name":"Christine Fr\u00f6schl","description":"Dein pers\u00f6nlicher Logenplatz im SalzburgerLand? Am liebsten gehe ich auf den Einberg im Salzburger Tennengau. Der Berg in der Osterhorn-Gruppe gl\u00e4nzt das ganze Jahr im Sonnenschein, auf dem Gipfel heben Paragleiter ab und die Aussicht auf das Tennengebirge, den Dachstein und die Bischofsm\u00fctze ist traumhaft. Dosige(r) oder Zuagroast? Zuagroast aus dem sch\u00f6nen Nieder\u00f6sterreich. Fr\u00fchling, Sommer, Herbst oder Winter? Alle Jahreszeiten begeistern mich. Momentan freue ich mich auf den Fr\u00fchling, das Zwitschern der V\u00f6gel und auf die sattgr\u00fcnen Wiesen. Salzburger Nockerl oder Schwarzbeernocken? Eindeutig Schwarzbeernocken. Rindsroulade vom Pinzgauer Biorind oder Saibling fangfrisch aus dem Fuschlsee? Mhhhh. Da kann ich mich nicht entscheiden. Bergtour oder Seentour? Mich zieht es auf jeden Fall hinauf. Begeistert bin ich auch von tiefblauen Bergseen in denen sich die Umgebung spiegelt und von der Aussicht w\u00e4hrend des Weges auf einen der wundersch\u00f6nen Seen im Salzburger Land.","url":"https:\/\/www.salzburgerland.com\/de\/magazin\/author\/christine-froeschl\/"}]}},"_wl_alt_label":[],"wl:entity_url":"http:\/\/open.salzburgerland.com\/magazin\/post\/salzburger_waldsalz_aus_untereggs_kraeutergartl","_links":{"self":[{"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/posts\/100622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/users\/236"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/comments?post=100622"}],"version-history":[{"count":0,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/posts\/100622\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/media\/100626"}],"wp:attachment":[{"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/media?parent=100622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/categories?post=100622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/tags?post=100622"},{"taxonomy":"wl_entity_type","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/wl_entity_type?post=100622"},{"taxonomy":"monatsauswahl","embeddable":true,"href":"https:\/\/www.salzburgerland.com\/de\/magazin\/wp-json\/wp\/v2\/monatsauswahl?post=100622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}